{"id":15245,"date":"2023-10-02T09:21:22","date_gmt":"2023-10-02T09:21:22","guid":{"rendered":"https:\/\/sicanivillages.com\/zu-pietro-le-sculpteur-qui-sculpte-en-memoire\/"},"modified":"2025-02-25T10:45:41","modified_gmt":"2025-02-25T10:45:41","slug":"zu-pietro-le-sculpteur-qui-sculpte-en-memoire","status":"publish","type":"post","link":"https:\/\/sicanivillages.com\/fr\/zu-pietro-le-sculpteur-qui-sculpte-en-memoire\/","title":{"rendered":"Zu Pietro, le sculpteur qui sculpte en m\u00e9moire"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"15245\" class=\"elementor elementor-15245 elementor-150\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1743bb46 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1743bb46\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4fe7966\" data-id=\"4fe7966\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1c16676 elementor-widget elementor-widget-image\" data-id=\"1c16676\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.19.0 - 07-02-2024 *\/\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" width=\"1440\" height=\"960\" src=\"https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/10\/Zio-Pietro-8.jpg\" class=\"elementor-animation-sink attachment-full size-full wp-image-9294\" alt=\"\" srcset=\"https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/10\/Zio-Pietro-8.jpg 1440w, https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/10\/Zio-Pietro-8-300x200.jpg 300w, https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/10\/Zio-Pietro-8-1024x683.jpg 1024w, https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/10\/Zio-Pietro-8-768x512.jpg 768w, https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/10\/Zio-Pietro-8-600x400.jpg 600w\" sizes=\"(max-width: 1440px) 100vw, 1440px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-485115e elementor-widget elementor-widget-text-editor\" data-id=\"485115e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.19.0 - 07-02-2024 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t\n<h4><span style=\"color: #0060a8;\">Rencontres et personnalit\u00e9s de la Terre Sicane<\/span><\/h4>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-03a3392 elementor-widget elementor-widget-text-editor\" data-id=\"03a3392\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h1>Zu Pietro, le sculpteur qui sculpte en m\u00e9moire<\/h1>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-13a95df5 elementor-widget elementor-widget-text-editor\" data-id=\"13a95df5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\n<h5><strong>Il a plus de 90 ans, vit \u00e0 Giuliana et sculpte le bois au jug\u00e9.<\/strong><\/h5>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f35f526 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f35f526\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-52100c0\" data-id=\"52100c0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-762fe9a elementor-widget elementor-widget-text-editor\" data-id=\"762fe9a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\n<p><strong>Le monde paysan sculpt\u00e9 dans le bois.<\/strong> <br>Semailles, r\u00e9coltes, animaux en p\u00e2ture, mais aussi figures hi\u00e9ratiques rappelant les statuettes votives de l&rsquo;art antique ou les bas-reliefs avec vues de la Sicile.<\/p>\n<p>L&rsquo;univers cr\u00e9atif de <strong>Pietro Principato<\/strong>, sculpteur-agriculteur, a ses racines bien ancr\u00e9es \u00e0 Giuliana. Un lien profond avec le village agricole de l&rsquo;extr\u00eame sud de Palerme, o\u00f9<strong>\u00ab\u00a0l&rsquo;oncle Pietro<\/strong>\u00a0\u00bb &#8211; comme tout le monde l&rsquo;appelle dans le village &#8211; est n\u00e9 en mai 1930. Ce sont des mains qui sculptent un monde qui se meurt, un travail dur, celui des champs et du b\u00e9tail, que Pietro a connu dans sa jeunesse. Du moins jusqu&rsquo;en 1964, date \u00e0 laquelle, malgr\u00e9 ses liens \u00e9troits avec sa patrie, il \u00e9migre en Allemagne, comme beaucoup d&rsquo;autres, \u00e0 la recherche de la fortune.   <\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a688a43 elementor-widget elementor-widget-image-carousel\" data-id=\"a688a43\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;2&quot;,&quot;slides_to_scroll&quot;:&quot;2&quot;,&quot;navigation&quot;:&quot;none&quot;,&quot;autoplay&quot;:&quot;no&quot;,&quot;infinite&quot;:&quot;no&quot;,&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:15,&quot;sizes&quot;:[]},&quot;speed&quot;:500,&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.19.0 - 07-02-2024 *\/\n.elementor-widget-image-carousel .swiper,.elementor-widget-image-carousel .swiper-container{position:static}.elementor-widget-image-carousel .swiper-container .swiper-slide figure,.elementor-widget-image-carousel .swiper .swiper-slide figure{line-height:inherit}.elementor-widget-image-carousel .swiper-slide{text-align:center}.elementor-image-carousel-wrapper:not(.swiper-container-initialized):not(.swiper-initialized) .swiper-slide{max-width:calc(100% \/ var(--e-image-carousel-slides-to-show, 3))}<\/style>\t\t<div class=\"elementor-image-carousel-wrapper swiper\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"polite\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 sur 2\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"a688a43\" data-elementor-lightbox-title=\"Zio Pietro (1)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6OTMwMSwidXJsIjoiaHR0cHM6XC9cL3NpY2FuaXZpbGxhZ2VzLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyM1wvMTBcL1ppby1QaWV0cm8tMS5qcGciLCJzbGlkZXNob3ciOiJhNjg4YTQzIn0%3D\" href=\"https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/10\/Zio-Pietro-1.jpg\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/10\/Zio-Pietro-1.jpg\" alt=\"Zio Pietro (1)\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 sur 2\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"a688a43\" data-elementor-lightbox-title=\"Zio Pietro (2)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6OTMwMiwidXJsIjoiaHR0cHM6XC9cL3NpY2FuaXZpbGxhZ2VzLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyM1wvMTBcL1ppby1QaWV0cm8tMi5qcGciLCJzbGlkZXNob3ciOiJhNjg4YTQzIn0%3D\" href=\"https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/10\/Zio-Pietro-2.jpg\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/10\/Zio-Pietro-2.jpg\" alt=\"Zio Pietro (2)\" \/><\/figure><\/a><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2046669 elementor-widget elementor-widget-text-editor\" data-id=\"2046669\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\n<p>Des adieux marqu\u00e9s par un accident de travail qui allait changer sa vie. En 1967, il est victime d&rsquo;un traumatisme de la colonne vert\u00e9brale et subit de nombreuses op\u00e9rations qui l&rsquo;obligent \u00e0 rester en fauteuil roulant pendant un certain temps. Neuf ans plus tard, en 1973, Pietro retourne en Sicile et commence peu apr\u00e8s l&rsquo;aventure artistique qui l&rsquo;accompagnera tout au long de sa vie, jusqu&rsquo;\u00e0 aujourd&rsquo;hui.  <\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-23d9538 elementor-widget elementor-widget-image-carousel\" data-id=\"23d9538\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;2&quot;,&quot;slides_to_scroll&quot;:&quot;2&quot;,&quot;navigation&quot;:&quot;none&quot;,&quot;autoplay&quot;:&quot;no&quot;,&quot;infinite&quot;:&quot;no&quot;,&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:15,&quot;sizes&quot;:[]},&quot;speed&quot;:500,&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"polite\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 sur 2\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"23d9538\" data-elementor-lightbox-title=\"Zio Pietro (3)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6OTMwMywidXJsIjoiaHR0cHM6XC9cL3NpY2FuaXZpbGxhZ2VzLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyM1wvMTBcL1ppby1QaWV0cm8tMy5qcGciLCJzbGlkZXNob3ciOiIyM2Q5NTM4In0%3D\" href=\"https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/10\/Zio-Pietro-3.jpg\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/10\/Zio-Pietro-3.jpg\" alt=\"Zio Pietro (3)\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 sur 2\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"23d9538\" data-elementor-lightbox-title=\"Zio Pietro (4)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6OTMwNCwidXJsIjoiaHR0cHM6XC9cL3NpY2FuaXZpbGxhZ2VzLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyM1wvMTBcL1ppby1QaWV0cm8tNC5qcGciLCJzbGlkZXNob3ciOiIyM2Q5NTM4In0%3D\" href=\"https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/10\/Zio-Pietro-4.jpg\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/10\/Zio-Pietro-4.jpg\" alt=\"Zio Pietro (4)\" \/><\/figure><\/a><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fb2c882 elementor-widget elementor-widget-text-editor\" data-id=\"fb2c882\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\n<p>Il raconte \u00e0 ceux qui le rencontrent sur le pas de sa porte que sculpter le bois le ram\u00e8ne avec nostalgie \u00e0 sa jeunesse, pass\u00e9e au milieu des champs et des animaux. Comme tous les artistes autodidactes, il vit l&rsquo;exp\u00e9rience cr\u00e9ative sans filtre ni fioriture. Il sculpte en bas-relief avec des moyens techniques rudimentaires, en premier lieu le couteau, avec lequel il sculpte principalement des planches d&rsquo;olivier ou de noyer.  <\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8c1bdea elementor-widget elementor-widget-image-carousel\" data-id=\"8c1bdea\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;3&quot;,&quot;slides_to_scroll&quot;:&quot;2&quot;,&quot;navigation&quot;:&quot;none&quot;,&quot;autoplay&quot;:&quot;no&quot;,&quot;infinite&quot;:&quot;no&quot;,&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:15,&quot;sizes&quot;:[]},&quot;speed&quot;:500,&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"polite\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 sur 3\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"8c1bdea\" data-elementor-lightbox-title=\"Zio Pietro (4)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6OTMwNCwidXJsIjoiaHR0cHM6XC9cL3NpY2FuaXZpbGxhZ2VzLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyM1wvMTBcL1ppby1QaWV0cm8tNC5qcGciLCJzbGlkZXNob3ciOiI4YzFiZGVhIn0%3D\" href=\"https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/10\/Zio-Pietro-4.jpg\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/10\/Zio-Pietro-4.jpg\" alt=\"Zio Pietro (4)\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 sur 3\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"8c1bdea\" data-elementor-lightbox-title=\"Zio Pietro (5)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6OTMwNSwidXJsIjoiaHR0cHM6XC9cL3NpY2FuaXZpbGxhZ2VzLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyM1wvMTBcL1ppby1QaWV0cm8tNS5qcGciLCJzbGlkZXNob3ciOiI4YzFiZGVhIn0%3D\" href=\"https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/10\/Zio-Pietro-5.jpg\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/10\/Zio-Pietro-5.jpg\" alt=\"Zio Pietro (5)\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 sur 3\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"8c1bdea\" data-elementor-lightbox-title=\"Zio Pietro (7)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6OTMwNywidXJsIjoiaHR0cHM6XC9cL3NpY2FuaXZpbGxhZ2VzLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyM1wvMTBcL1ppby1QaWV0cm8tNy5qcGciLCJzbGlkZXNob3ciOiI4YzFiZGVhIn0%3D\" href=\"https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/10\/Zio-Pietro-7.jpg\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/10\/Zio-Pietro-7.jpg\" alt=\"Zio Pietro (7)\" \/><\/figure><\/a><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6c86d88 elementor-widget elementor-widget-text-editor\" data-id=\"6c86d88\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><\/p>\n<p>Sa technique est totalement spontan\u00e9e, il ne conna\u00eet pas les lois de la perspective et du raccourcissement, mais c&rsquo;est pr\u00e9cis\u00e9ment pour cette raison que ses \u0153uvres apparaissent sinc\u00e8res et directes, parfois \u00e9vocatrices : des figures n\u00e9es de son imagination inn\u00e9e ou, comme il le dit lui-m\u00eame : \u00ab\u00a0Guessing\u00a0\u00bb (en fran\u00e7ais : \u00ab\u00a0deviner\u00a0\u00bb).<\/p>\n<p>Rencontrer Pietro &#8211; l&rsquo;un des nombreux visages vrais et profonds que l&rsquo;on peut croiser en explorant la Terre Sicane &#8211; entendre de sa voix la gen\u00e8se de chaque \u0153uvre qu&rsquo;il a sculpt\u00e9e, c&rsquo;est faire un fantastique voyage dans la m\u00e9moire. Un art spontan\u00e9, mais avec un processus cr\u00e9atif rigoureux, qui est une ode au temps qui passe. <\/p>\n<p><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3657843 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3657843\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-5bf56df\" data-id=\"5bf56df\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-45c2e42 elementor-widget elementor-widget-image\" data-id=\"45c2e42\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img width=\"150\" height=\"150\" src=\"https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/10\/Giulio-Giallombardo-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-image-9284\" alt=\"\" srcset=\"https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/10\/Giulio-Giallombardo-150x150.jpg 150w, https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/10\/Giulio-Giallombardo-306x306.jpg 306w, https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/10\/Giulio-Giallombardo-300x300.jpg 300w, https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/10\/Giulio-Giallombardo-100x100.jpg 100w, https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/10\/elementor\/thumbs\/Giulio-Giallombardo-qd9vwbhm5ugzyl68s7dhswhroww0fdriez4nxih3n4.jpg 120w, https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/10\/elementor\/thumbs\/Giulio-Giallombardo-qd9vwbhmem8aa6sznzjq849fwdqc5qenlc1p5skjnc.jpg 140w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-37adc50 elementor-widget elementor-widget-text-editor\" data-id=\"37adc50\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Texte et photos de <strong>Giulio Giallombardo<\/strong><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-a3c9449\" data-id=\"a3c9449\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-78f8311\" data-id=\"78f8311\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-e753b67\" data-id=\"e753b67\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>  Rencontres et personnalit\u00e9s de la Terre Sicane<\/p>\n","protected":false},"author":5,"featured_media":12048,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","footnotes":""},"categories":[183],"tags":[],"mese":[],"paese":[],"tipologia":[],"class_list":["post-15245","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articles-en-vedette"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Zu Pietro, le sculpteur qui sculpte en m\u00e9moire - SicaniVillages<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sicanivillages.com\/fr\/zu-pietro-le-sculpteur-qui-sculpte-en-memoire\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Zu Pietro, le sculpteur qui sculpte en m\u00e9moire - SicaniVillages\" \/>\n<meta property=\"og:description\" content=\"Rencontres et personnalit\u00e9s de la Terre Sicane\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sicanivillages.com\/fr\/zu-pietro-le-sculpteur-qui-sculpte-en-memoire\/\" \/>\n<meta property=\"og:site_name\" content=\"SicaniVillages\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-02T09:21:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-25T10:45:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/10\/Zio-Pietro-8.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1440\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Giulio Giallombardo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Giulio Giallombardo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/sicanivillages.com\/fr\/zu-pietro-le-sculpteur-qui-sculpte-en-memoire\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/sicanivillages.com\/fr\/zu-pietro-le-sculpteur-qui-sculpte-en-memoire\/\"},\"author\":{\"name\":\"Giulio Giallombardo\",\"@id\":\"https:\/\/sicanivillages.com\/#\/schema\/person\/785395abf3558eae44aad86cb5e53303\"},\"headline\":\"Zu Pietro, le sculpteur qui sculpte en m\u00e9moire\",\"datePublished\":\"2023-10-02T09:21:22+00:00\",\"dateModified\":\"2025-02-25T10:45:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/sicanivillages.com\/fr\/zu-pietro-le-sculpteur-qui-sculpte-en-memoire\/\"},\"wordCount\":452,\"image\":{\"@id\":\"https:\/\/sicanivillages.com\/fr\/zu-pietro-le-sculpteur-qui-sculpte-en-memoire\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/10\/Zio-Pietro-8.jpg\",\"articleSection\":[\"Articles en vedette\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/sicanivillages.com\/fr\/zu-pietro-le-sculpteur-qui-sculpte-en-memoire\/\",\"url\":\"https:\/\/sicanivillages.com\/fr\/zu-pietro-le-sculpteur-qui-sculpte-en-memoire\/\",\"name\":\"Zu Pietro, le sculpteur qui sculpte en m\u00e9moire - SicaniVillages\",\"isPartOf\":{\"@id\":\"https:\/\/sicanivillages.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/sicanivillages.com\/fr\/zu-pietro-le-sculpteur-qui-sculpte-en-memoire\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/sicanivillages.com\/fr\/zu-pietro-le-sculpteur-qui-sculpte-en-memoire\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/10\/Zio-Pietro-8.jpg\",\"datePublished\":\"2023-10-02T09:21:22+00:00\",\"dateModified\":\"2025-02-25T10:45:41+00:00\",\"author\":{\"@id\":\"https:\/\/sicanivillages.com\/#\/schema\/person\/785395abf3558eae44aad86cb5e53303\"},\"breadcrumb\":{\"@id\":\"https:\/\/sicanivillages.com\/fr\/zu-pietro-le-sculpteur-qui-sculpte-en-memoire\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/sicanivillages.com\/fr\/zu-pietro-le-sculpteur-qui-sculpte-en-memoire\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/sicanivillages.com\/fr\/zu-pietro-le-sculpteur-qui-sculpte-en-memoire\/#primaryimage\",\"url\":\"https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/10\/Zio-Pietro-8.jpg\",\"contentUrl\":\"https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/10\/Zio-Pietro-8.jpg\",\"width\":1440,\"height\":960},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/sicanivillages.com\/fr\/zu-pietro-le-sculpteur-qui-sculpte-en-memoire\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/sicanivillages.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Zu Pietro, le sculpteur qui sculpte en m\u00e9moire\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/sicanivillages.com\/#website\",\"url\":\"https:\/\/sicanivillages.com\/\",\"name\":\"SicaniVillages\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/sicanivillages.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/sicanivillages.com\/#\/schema\/person\/785395abf3558eae44aad86cb5e53303\",\"name\":\"Giulio Giallombardo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/sicanivillages.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7901e4b27fa2bbcd571cec7f850077689277e3c4e4599843052b97ce08b806ff?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7901e4b27fa2bbcd571cec7f850077689277e3c4e4599843052b97ce08b806ff?s=96&d=mm&r=g\",\"caption\":\"Giulio Giallombardo\"},\"url\":\"https:\/\/sicanivillages.com\/fr\/author\/giulio-giallombardo\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Zu Pietro, le sculpteur qui sculpte en m\u00e9moire - SicaniVillages","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sicanivillages.com\/fr\/zu-pietro-le-sculpteur-qui-sculpte-en-memoire\/","og_locale":"fr_FR","og_type":"article","og_title":"Zu Pietro, le sculpteur qui sculpte en m\u00e9moire - SicaniVillages","og_description":"Rencontres et personnalit\u00e9s de la Terre Sicane","og_url":"https:\/\/sicanivillages.com\/fr\/zu-pietro-le-sculpteur-qui-sculpte-en-memoire\/","og_site_name":"SicaniVillages","article_published_time":"2023-10-02T09:21:22+00:00","article_modified_time":"2025-02-25T10:45:41+00:00","og_image":[{"width":1440,"height":960,"url":"https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/10\/Zio-Pietro-8.jpg","type":"image\/jpeg"}],"author":"Giulio Giallombardo","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Giulio Giallombardo","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sicanivillages.com\/fr\/zu-pietro-le-sculpteur-qui-sculpte-en-memoire\/#article","isPartOf":{"@id":"https:\/\/sicanivillages.com\/fr\/zu-pietro-le-sculpteur-qui-sculpte-en-memoire\/"},"author":{"name":"Giulio Giallombardo","@id":"https:\/\/sicanivillages.com\/#\/schema\/person\/785395abf3558eae44aad86cb5e53303"},"headline":"Zu Pietro, le sculpteur qui sculpte en m\u00e9moire","datePublished":"2023-10-02T09:21:22+00:00","dateModified":"2025-02-25T10:45:41+00:00","mainEntityOfPage":{"@id":"https:\/\/sicanivillages.com\/fr\/zu-pietro-le-sculpteur-qui-sculpte-en-memoire\/"},"wordCount":452,"image":{"@id":"https:\/\/sicanivillages.com\/fr\/zu-pietro-le-sculpteur-qui-sculpte-en-memoire\/#primaryimage"},"thumbnailUrl":"https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/10\/Zio-Pietro-8.jpg","articleSection":["Articles en vedette"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/sicanivillages.com\/fr\/zu-pietro-le-sculpteur-qui-sculpte-en-memoire\/","url":"https:\/\/sicanivillages.com\/fr\/zu-pietro-le-sculpteur-qui-sculpte-en-memoire\/","name":"Zu Pietro, le sculpteur qui sculpte en m\u00e9moire - SicaniVillages","isPartOf":{"@id":"https:\/\/sicanivillages.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sicanivillages.com\/fr\/zu-pietro-le-sculpteur-qui-sculpte-en-memoire\/#primaryimage"},"image":{"@id":"https:\/\/sicanivillages.com\/fr\/zu-pietro-le-sculpteur-qui-sculpte-en-memoire\/#primaryimage"},"thumbnailUrl":"https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/10\/Zio-Pietro-8.jpg","datePublished":"2023-10-02T09:21:22+00:00","dateModified":"2025-02-25T10:45:41+00:00","author":{"@id":"https:\/\/sicanivillages.com\/#\/schema\/person\/785395abf3558eae44aad86cb5e53303"},"breadcrumb":{"@id":"https:\/\/sicanivillages.com\/fr\/zu-pietro-le-sculpteur-qui-sculpte-en-memoire\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sicanivillages.com\/fr\/zu-pietro-le-sculpteur-qui-sculpte-en-memoire\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/sicanivillages.com\/fr\/zu-pietro-le-sculpteur-qui-sculpte-en-memoire\/#primaryimage","url":"https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/10\/Zio-Pietro-8.jpg","contentUrl":"https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/10\/Zio-Pietro-8.jpg","width":1440,"height":960},{"@type":"BreadcrumbList","@id":"https:\/\/sicanivillages.com\/fr\/zu-pietro-le-sculpteur-qui-sculpte-en-memoire\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sicanivillages.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Zu Pietro, le sculpteur qui sculpte en m\u00e9moire"}]},{"@type":"WebSite","@id":"https:\/\/sicanivillages.com\/#website","url":"https:\/\/sicanivillages.com\/","name":"SicaniVillages","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sicanivillages.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/sicanivillages.com\/#\/schema\/person\/785395abf3558eae44aad86cb5e53303","name":"Giulio Giallombardo","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/sicanivillages.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/7901e4b27fa2bbcd571cec7f850077689277e3c4e4599843052b97ce08b806ff?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7901e4b27fa2bbcd571cec7f850077689277e3c4e4599843052b97ce08b806ff?s=96&d=mm&r=g","caption":"Giulio Giallombardo"},"url":"https:\/\/sicanivillages.com\/fr\/author\/giulio-giallombardo\/"}]}},"_links":{"self":[{"href":"https:\/\/sicanivillages.com\/fr\/wp-json\/wp\/v2\/posts\/15245","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sicanivillages.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sicanivillages.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sicanivillages.com\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/sicanivillages.com\/fr\/wp-json\/wp\/v2\/comments?post=15245"}],"version-history":[{"count":3,"href":"https:\/\/sicanivillages.com\/fr\/wp-json\/wp\/v2\/posts\/15245\/revisions"}],"predecessor-version":[{"id":15254,"href":"https:\/\/sicanivillages.com\/fr\/wp-json\/wp\/v2\/posts\/15245\/revisions\/15254"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sicanivillages.com\/fr\/wp-json\/wp\/v2\/media\/12048"}],"wp:attachment":[{"href":"https:\/\/sicanivillages.com\/fr\/wp-json\/wp\/v2\/media?parent=15245"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sicanivillages.com\/fr\/wp-json\/wp\/v2\/categories?post=15245"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sicanivillages.com\/fr\/wp-json\/wp\/v2\/tags?post=15245"},{"taxonomy":"mese","embeddable":true,"href":"https:\/\/sicanivillages.com\/fr\/wp-json\/wp\/v2\/mese?post=15245"},{"taxonomy":"paese","embeddable":true,"href":"https:\/\/sicanivillages.com\/fr\/wp-json\/wp\/v2\/paese?post=15245"},{"taxonomy":"tipologia","embeddable":true,"href":"https:\/\/sicanivillages.com\/fr\/wp-json\/wp\/v2\/tipologia?post=15245"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}