{"id":14906,"date":"2024-03-11T12:26:44","date_gmt":"2024-03-11T12:26:44","guid":{"rendered":"https:\/\/sicanivillages.com\/santangelo-muxaro-accueille-le-premier-festival-consacre-a-lasperge-sauvage-sicilienne\/"},"modified":"2025-02-24T12:29:38","modified_gmt":"2025-02-24T12:29:38","slug":"santangelo-muxaro-accueille-le-premier-festival-consacre-a-lasperge-sauvage-sicilienne","status":"publish","type":"post","link":"https:\/\/sicanivillages.com\/fr\/santangelo-muxaro-accueille-le-premier-festival-consacre-a-lasperge-sauvage-sicilienne\/","title":{"rendered":"Sant&rsquo;Angelo Muxaro accueille le premier festival consacr\u00e9 \u00e0 l&rsquo;asperge sauvage sicilienne"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"14906\" class=\"elementor elementor-14906 elementor-11131\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1743bb46 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1743bb46\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4fe7966\" data-id=\"4fe7966\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1c16676 elementor-widget elementor-widget-image\" data-id=\"1c16676\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.19.0 - 07-02-2024 *\/\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" width=\"1534\" height=\"1227\" src=\"https:\/\/sicanivillages.com\/wp-content\/uploads\/2024\/03\/Sicani-Anna-Rizzuti-la-ragazza-che-ha-prestato-il-suo-volto-per-la-locandina-della-sagra.jpg\" class=\"elementor-animation-sink attachment-full size-full wp-image-11133\" alt=\"\" srcset=\"https:\/\/sicanivillages.com\/wp-content\/uploads\/2024\/03\/Sicani-Anna-Rizzuti-la-ragazza-che-ha-prestato-il-suo-volto-per-la-locandina-della-sagra.jpg 1534w, https:\/\/sicanivillages.com\/wp-content\/uploads\/2024\/03\/Sicani-Anna-Rizzuti-la-ragazza-che-ha-prestato-il-suo-volto-per-la-locandina-della-sagra-300x240.jpg 300w, https:\/\/sicanivillages.com\/wp-content\/uploads\/2024\/03\/Sicani-Anna-Rizzuti-la-ragazza-che-ha-prestato-il-suo-volto-per-la-locandina-della-sagra-1024x819.jpg 1024w, https:\/\/sicanivillages.com\/wp-content\/uploads\/2024\/03\/Sicani-Anna-Rizzuti-la-ragazza-che-ha-prestato-il-suo-volto-per-la-locandina-della-sagra-768x614.jpg 768w, https:\/\/sicanivillages.com\/wp-content\/uploads\/2024\/03\/Sicani-Anna-Rizzuti-la-ragazza-che-ha-prestato-il-suo-volto-per-la-locandina-della-sagra-600x480.jpg 600w\" sizes=\"(max-width: 1534px) 100vw, 1534px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-485115e elementor-widget elementor-widget-text-editor\" data-id=\"485115e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.19.0 - 07-02-2024 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<p><\/p>\n<h4>L&rsquo;excellence du territoire<\/h4>\n<p><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-03a3392 elementor-widget elementor-widget-text-editor\" data-id=\"03a3392\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h1>A Sant&rsquo;Angelo Muxaro<br>le premier festival d\u00e9di\u00e9<br>\u00e0 l&rsquo;asperge sauvage sicilienne.<\/h1>\n<div> <\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-13a95df5 elementor-widget elementor-widget-text-editor\" data-id=\"13a95df5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\n<h5>Samedi 13 et dimanche 14 avril<br>grande f\u00eate avec show cooking <br>d\u00e9gustations et excursions  <\/h5>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f35f526 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f35f526\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-52100c0\" data-id=\"52100c0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-a607276 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a607276\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-38e71f0\" data-id=\"38e71f0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-710bd6a\" data-id=\"710bd6a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-762fe9a elementor-widget elementor-widget-text-editor\" data-id=\"762fe9a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\n<p>Si vous avez un ami de Sant&rsquo;Angelo Muxaro et que les asperges sont votre passion, vous savez, c&rsquo;est fini. Avec la tranquillit\u00e9 d&rsquo;esprit de l&rsquo;ami, car, de gr\u00e9 ou de force, il sera \u00ab\u00a0oblig\u00e9\u00a0\u00bb de vous laisser d\u00e9guster ces d\u00e9lices d&rsquo;asperges championnes, qui poussent en abondance dans la campagne de <strong>Sant&rsquo;Angelo Muxaro<\/strong>. <br>Une excellence du territoire qui s&rsquo;est \u00e9galement retrouv\u00e9e dans le programme \u00e9lectoral du jeune maire <strong>Angelo Tirrito,<\/strong> 33 ans le 2 juin prochain et qui en est \u00e0 son deuxi\u00e8me mandat. <strong>La premi\u00e8re Sagra dell&rsquo;asparago selvatico sicano (f\u00eate de l&rsquo;asperge sauvage de Sican<\/strong> ), qui se tiendra dans le petit village de la r\u00e9gion d&rsquo;Agrigente les samedi 13 et dimanche 14 avril, a en effet \u00e9t\u00e9 l&rsquo;un des chevaux de bataille de sa campagne \u00e9lectorale pour les \u00e9lections locales de l&rsquo;ann\u00e9e derni\u00e8re. Selon les intentions de l&rsquo;administration communale et des promoteurs de l&rsquo;\u00e9v\u00e9nement, la f\u00eate ne se veut pas seulement une grande f\u00eate d\u00e9di\u00e9e \u00e0 un excellent produit riche en vitamines, min\u00e9raux, fibres et aux propri\u00e9t\u00e9s diur\u00e9tiques et d\u00e9puratives bien connues, mais le moteur d&rsquo;une nouvelle aventure : la culture de l&rsquo;asperge sauvage sicilienne.    <br>Dans notre r\u00e9gion, explique le maire Angelo Tirrito, il existe d\u00e9j\u00e0 des cultures exp\u00e9rimentales d&rsquo;asperges sauvages siciliennes, et l&rsquo;on a d\u00e9j\u00e0 constat\u00e9 que les caract\u00e9ristiques typiques de l&rsquo;asperge sont \u00e9galement conserv\u00e9es dans le produit cultiv\u00e9.<br>\u00ab\u00a0En outre, affirme <strong>Pierfilippo Spoto,<\/strong> cr\u00e9ateur et l&rsquo;un des promoteurs de l&rsquo;initiative, la communaut\u00e9 europ\u00e9enne voit d&rsquo;un bon \u0153il sa culture ; il ne reste donc plus qu&rsquo;\u00e0 promouvoir ce produit si caract\u00e9ristique de notre territoire qu&rsquo;il est mentionn\u00e9 dans plus d&rsquo;un proverbe.<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a688a43 elementor-widget elementor-widget-image-carousel\" data-id=\"a688a43\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;none&quot;,&quot;autoplay&quot;:&quot;no&quot;,&quot;infinite&quot;:&quot;no&quot;,&quot;slides_to_show_mobile&quot;:&quot;1&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.19.0 - 07-02-2024 *\/\n.elementor-widget-image-carousel .swiper,.elementor-widget-image-carousel .swiper-container{position:static}.elementor-widget-image-carousel .swiper-container .swiper-slide figure,.elementor-widget-image-carousel .swiper .swiper-slide figure{line-height:inherit}.elementor-widget-image-carousel .swiper-slide{text-align:center}.elementor-image-carousel-wrapper:not(.swiper-container-initialized):not(.swiper-initialized) .swiper-slide{max-width:calc(100% \/ var(--e-image-carousel-slides-to-show, 3))}<\/style>\t\t<div class=\"elementor-image-carousel-wrapper swiper\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"polite\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 sur 1\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"a688a43\" data-elementor-lightbox-title=\"Sicani - Il sindaco di Sant&#039;Angelo Muxaro, Angelo Tirrito\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTExMzUsInVybCI6Imh0dHBzOlwvXC9zaWNhbml2aWxsYWdlcy5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzAzXC9TaWNhbmktSWwtc2luZGFjby1kaS1TYW50QW5nZWxvLU11eGFyby1BbmdlbG8tVGlycml0by5qcGciLCJzbGlkZXNob3ciOiJhNjg4YTQzIn0%3D\" href=\"https:\/\/sicanivillages.com\/wp-content\/uploads\/2024\/03\/Sicani-Il-sindaco-di-SantAngelo-Muxaro-Angelo-Tirrito.jpg\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/sicanivillages.com\/wp-content\/uploads\/2024\/03\/Sicani-Il-sindaco-di-SantAngelo-Muxaro-Angelo-Tirrito-768x660.jpg\" alt=\"Il sindaco di Sant&#039;Angelo Muxaro, Angelo Tirrito\" \/><figcaption class=\"elementor-image-carousel-caption\"> Il sindaco di Sant'Angelo Muxaro, Angelo Tirrito<\/figcaption><\/figure><\/a><\/div>\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2046669 elementor-widget elementor-widget-text-editor\" data-id=\"2046669\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><\/p>\n<p>LE PROGRAMME. Organis\u00e9e par la commune de Sant&rsquo;Angelo Muxaro avec Val di Kam et le Distretto rurale di qualit\u00e0 Sicani, la premi\u00e8re Sagra dell&rsquo;asparago selvatico sicano (f\u00eate de l&rsquo;asperge sauvage de Sican) se d\u00e9roulera sur la place principale de la ville, la Piazza Umberto I. <br>Le samedi 13 avril, l&rsquo;ouverture aura lieu \u00e0 17 heures avec les salutations institutionnelles et une <strong>conf\u00e9rence consacr\u00e9e aux \u00ab\u00a0Tr\u00e9sors de la terre\u00a0\u00bb,<\/strong> organis\u00e9e par le conseil municipal de l&rsquo;agriculture et du tourisme. \u00c0 partir de 19 heures, <strong>musique en direct et d\u00e9gustations savoureuses<\/strong> o\u00f9 l&rsquo;asperge sauvage sicilienne sera le protagoniste de nombreuses recettes et d&rsquo;un g\u00e2teau original cr\u00e9\u00e9 par les p\u00e2tissiers de Sant&rsquo;Angelo, sp\u00e9cialement pour l&rsquo;occasion. <br>Le dimanche 14 avril, tout commencera t\u00f4t, \u00e0 9 heures, avec une <strong>randonn\u00e9e \u00ab\u00a0Sur les traces du roi sicilien Kokalos\u00a0\u00bb,<\/strong> organis\u00e9e par l&rsquo;association Sicani Outdoor. Avec Legambiente, en revanche, il sera possible d&rsquo;explorer le <strong>Vallone del Ponte<\/strong> avec la <strong>Grotta Ciauli<\/strong> et d&rsquo;admirer la flore et la faune qui animent la rivi\u00e8re souterraine, affluent du Platani.     <br>Pendant ce temps, sur la Piazza Umberto I, la<strong>zone des stands<\/strong>sera ouverte et \u00e0 9h30 aura lieu une<strong>rencontre organis\u00e9e par Slow Food Agrigento,<\/strong> consacr\u00e9e \u00e0 l&rsquo;utilisation des herbes et arbustes sauvages dans la cuisine et l&rsquo;artisanat ; elle sera suivie d&rsquo;un<strong> show cooking<\/strong>, organis\u00e9 par la trattoria Borgetto di Joppolo Giancaxio, qui pr\u00e9parera un savoureux velout\u00e9 d&rsquo;asperges sauvages siciliennes sur une cro\u00fbte de pain.<br>\u00c0 10h30, une<strong>rencontre sur \u00ab\u00a0La culture de l&rsquo;asperge sauvage dans le Sicani\u00a0\u00bb<\/strong> sera organis\u00e9e par le Studio Euromediterraneo de San Biagio Platani, \u00e0 laquelle participera \u00e9galement le professeur Giuseppe Di Miceli de la Facult\u00e9 d&rsquo;agriculture de l&rsquo;Universit\u00e9 de Palerme. \u00c0 partir de 11h30, les stands seront ouverts pour la <strong>d\u00e9gustation de<\/strong> plats tels que le macco de f\u00e8ves aux pointes d&rsquo;asperges sauvages, propos\u00e9 par le restaurant Marl\u00f2 de Raffadali ou les sandwichs gourmands de la Prosciutteria, \u00e9galement de Raffadali. Il existe \u00e9galement un plateau de d\u00e9gustation, de l&rsquo;entr\u00e9e au dessert, avec un verre de vin inclus, au prix modique de 5 euros.  <br>Dans l&rsquo;<strong>espace conf\u00e9rences,<\/strong> \u00e0 15h30, la commune de Sant&rsquo;Angelo Muxaro officialisera son adh\u00e9sion \u00e0 la Dmo (Destination Marketing Organisation) de la Vall\u00e9e des Temples ; \u00e0 16h30, place \u00e0 \u00ab\u00a0Sicani in progress\u00a0\u00bb, pour faire le point sur tous les projets qui concernent le territoire ; \u00e0 17h30, \u00ab\u00a0Quattro chiacchiere in cortile\u00a0\u00bb pour parler de \u00ab\u00a0Il tempo nei borghi, tra turismo e filosofia\u00a0\u00bb (Le temps dans les villages, entre tourisme et philosophie) avec Salvatore Presti et Pierfilippo Spoto.  <br>Et des mots aux verres, \u00e0 18h30, avec \u00ab\u00a0Un fiume DiVino\u00a0\u00bb, une <strong>d\u00e9gustation de vins produits dans la r\u00e9gion de Platani,<\/strong> organis\u00e9e par l&rsquo;Association des sommeliers italiens d&rsquo;Agrigente.  <br>La musique en direct interpr\u00e9t\u00e9e par les groupes les plus int\u00e9ressants et les plus repr\u00e9sentatifs de la r\u00e9gion constituera la bande sonore de l&rsquo;ensemble de l&rsquo;\u00e9v\u00e9nement.<\/p>\n<p><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-23d9538 elementor-widget elementor-widget-image-carousel\" data-id=\"23d9538\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;none&quot;,&quot;autoplay&quot;:&quot;no&quot;,&quot;infinite&quot;:&quot;no&quot;,&quot;slides_to_show_mobile&quot;:&quot;1&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"polite\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 sur 1\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"23d9538\" data-elementor-lightbox-title=\"Sicani - Da sinistra, Pierfilippo Spoto, Alessandro Spoto, Luca Barba e Carmelo Di Franco\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTExMzQsInVybCI6Imh0dHBzOlwvXC9zaWNhbml2aWxsYWdlcy5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzAzXC9TaWNhbmktRGEtc2luaXN0cmEtUGllcmZpbGlwcG8tU3BvdG8tQWxlc3NhbmRyby1TcG90by1MdWNhLUJhcmJhLWUtQ2FybWVsby1EaS1GcmFuY28tLmpwZyIsInNsaWRlc2hvdyI6IjIzZDk1MzgifQ%3D%3D\" href=\"https:\/\/sicanivillages.com\/wp-content\/uploads\/2024\/03\/Sicani-Da-sinistra-Pierfilippo-Spoto-Alessandro-Spoto-Luca-Barba-e-Carmelo-Di-Franco-.jpg\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/sicanivillages.com\/wp-content\/uploads\/2024\/03\/Sicani-Da-sinistra-Pierfilippo-Spoto-Alessandro-Spoto-Luca-Barba-e-Carmelo-Di-Franco--768x660.jpg\" alt=\"- Da sinistra, Pierfilippo Spoto, Alessandro Spoto, Luca Barba e Carmelo Di Franco\" \/><figcaption class=\"elementor-image-carousel-caption\">- Da sinistra, Pierfilippo Spoto, Alessandro Spoto, Luca Barba e Carmelo Di Franco <\/figcaption><\/figure><\/a><\/div>\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fb2c882 elementor-widget elementor-widget-text-editor\" data-id=\"fb2c882\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\n<p>Notre principal objectif\u00a0\u00bb, d\u00e9clare le maire Tirrito, \u00ab\u00a0outre le fait de v\u00e9hiculer le plus possible l&rsquo;image de Sant&rsquo;Angelo Muxaro, est la d\u00e9saisonnalisation des pr\u00e9sences. Dans les villages des Apennins plus petits que le n\u00f4tre, c&rsquo;est d\u00e9j\u00e0 le cas et les flux touristiques couvrent plus ou moins toute l&rsquo;ann\u00e9e. Il nous faut donc construire un circuit vertueux, activer des synergies. Entre les chambres d&rsquo;h\u00f4tes et les r\u00e9sidences secondaires, notre village compte une quarantaine de lits, mais nous travaillons d\u00e9j\u00e0 sur un projet d&rsquo;h\u00f4tel g\u00e9n\u00e9ralis\u00e9. En attendant, d&rsquo;ici juin, nous activerons la signal\u00e9tique interactive qui permettra, via une appli d\u00e9di\u00e9e et le syst\u00e8me de QR code, de conna\u00eetre les diff\u00e9rents parcours touristiques, en indiquant \u00e9galement leur accessibilit\u00e9 aux personnes handicap\u00e9es\u00a0\u00bb.<\/p>\n<p> <\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f1d432e elementor-widget elementor-widget-image-carousel\" data-id=\"f1d432e\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;none&quot;,&quot;autoplay&quot;:&quot;no&quot;,&quot;infinite&quot;:&quot;no&quot;,&quot;slides_to_show_mobile&quot;:&quot;1&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"polite\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 sur 1\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"f1d432e\" data-elementor-lightbox-title=\"Sicani - locandina asparago\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTExMzcsInVybCI6Imh0dHBzOlwvXC9zaWNhbml2aWxsYWdlcy5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzAzXC9TaWNhbmktbG9jYW5kaW5hLWFzcGFyYWdvLmpwZyIsInNsaWRlc2hvdyI6ImYxZDQzMmUifQ%3D%3D\" href=\"https:\/\/sicanivillages.com\/wp-content\/uploads\/2024\/03\/Sicani-locandina-asparago.jpg\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/sicanivillages.com\/wp-content\/uploads\/2024\/03\/Sicani-locandina-asparago-768x660.jpg\" alt=\"Locandina con Anna Rizzuti, la ragazza che ha prestato il suo volto per la locandina della sagra\" \/><figcaption class=\"elementor-image-carousel-caption\">Locandina con Anna Rizzuti, la ragazza che ha prestato il suo volto per la locandina della sagra<\/figcaption><\/figure><\/a><\/div>\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3657843 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3657843\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-5bf56df\" data-id=\"5bf56df\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-37adc50 elementor-widget elementor-widget-text-editor\" data-id=\"37adc50\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Texte d&rsquo;Angela Mannino<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-45c2e42 elementor-widget elementor-widget-image\" data-id=\"45c2e42\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img width=\"150\" height=\"150\" src=\"https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/10\/Angela-mannino-150x150.jpeg\" class=\"attachment-thumbnail size-thumbnail wp-image-9952\" alt=\"\" srcset=\"https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/10\/Angela-mannino-150x150.jpeg 150w, https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/10\/Angela-mannino-298x300.jpeg 298w, https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/10\/Angela-mannino-306x306.jpeg 306w, https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/10\/Angela-mannino-300x300.jpeg 300w, https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/10\/Angela-mannino-100x100.jpeg 100w, https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/10\/Angela-mannino.jpeg 600w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-a3c9449\" data-id=\"a3c9449\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-78f8311\" data-id=\"78f8311\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-e753b67\" data-id=\"e753b67\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Samedi 13 et dimanche 14 avril : grande f\u00eate avec spectacle, d\u00e9gustations culinaires et excursions.  <\/p>\n","protected":false},"author":6,"featured_media":12604,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","footnotes":""},"categories":[183,134],"tags":[],"mese":[],"paese":[],"tipologia":[],"class_list":["post-14906","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articles-en-vedette","category-non-classifiee"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Sant&#039;Angelo Muxaro accueille le premier festival consacr\u00e9 \u00e0 l&#039;asperge sauvage sicilienne - SicaniVillages<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sicanivillages.com\/fr\/santangelo-muxaro-accueille-le-premier-festival-consacre-a-lasperge-sauvage-sicilienne\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sant&#039;Angelo Muxaro accueille le premier festival consacr\u00e9 \u00e0 l&#039;asperge sauvage sicilienne - SicaniVillages\" \/>\n<meta property=\"og:description\" content=\"Samedi 13 et dimanche 14 avril : grande f\u00eate avec spectacle, d\u00e9gustations culinaires et excursions.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sicanivillages.com\/fr\/santangelo-muxaro-accueille-le-premier-festival-consacre-a-lasperge-sauvage-sicilienne\/\" \/>\n<meta property=\"og:site_name\" content=\"SicaniVillages\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-11T12:26:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-24T12:29:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sicanivillages.com\/wp-content\/uploads\/2024\/03\/Sicani-Anna-Rizzuti-la-ragazza-che-ha-prestato-il-suo-volto-per-la-locandina-della-sagra.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1534\" \/>\n\t<meta property=\"og:image:height\" content=\"1227\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Angela Mannino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Angela Mannino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/sicanivillages.com\/fr\/santangelo-muxaro-accueille-le-premier-festival-consacre-a-lasperge-sauvage-sicilienne\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/sicanivillages.com\/fr\/santangelo-muxaro-accueille-le-premier-festival-consacre-a-lasperge-sauvage-sicilienne\/\"},\"author\":{\"name\":\"Angela Mannino\",\"@id\":\"https:\/\/sicanivillages.com\/#\/schema\/person\/c11e3fc1b34e65666656600ff33eab56\"},\"headline\":\"Sant&rsquo;Angelo Muxaro accueille le premier festival consacr\u00e9 \u00e0 l&rsquo;asperge sauvage sicilienne\",\"datePublished\":\"2024-03-11T12:26:44+00:00\",\"dateModified\":\"2025-02-24T12:29:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/sicanivillages.com\/fr\/santangelo-muxaro-accueille-le-premier-festival-consacre-a-lasperge-sauvage-sicilienne\/\"},\"wordCount\":1041,\"image\":{\"@id\":\"https:\/\/sicanivillages.com\/fr\/santangelo-muxaro-accueille-le-premier-festival-consacre-a-lasperge-sauvage-sicilienne\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/sicanivillages.com\/wp-content\/uploads\/2024\/03\/Sicani-Anna-Rizzuti-la-ragazza-che-ha-prestato-il-suo-volto-per-la-locandina-della-sagra.jpg\",\"articleSection\":[\"Articles en vedette\",\"Non classifi\u00e9(e)\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/sicanivillages.com\/fr\/santangelo-muxaro-accueille-le-premier-festival-consacre-a-lasperge-sauvage-sicilienne\/\",\"url\":\"https:\/\/sicanivillages.com\/fr\/santangelo-muxaro-accueille-le-premier-festival-consacre-a-lasperge-sauvage-sicilienne\/\",\"name\":\"Sant'Angelo Muxaro accueille le premier festival consacr\u00e9 \u00e0 l'asperge sauvage sicilienne - SicaniVillages\",\"isPartOf\":{\"@id\":\"https:\/\/sicanivillages.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/sicanivillages.com\/fr\/santangelo-muxaro-accueille-le-premier-festival-consacre-a-lasperge-sauvage-sicilienne\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/sicanivillages.com\/fr\/santangelo-muxaro-accueille-le-premier-festival-consacre-a-lasperge-sauvage-sicilienne\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/sicanivillages.com\/wp-content\/uploads\/2024\/03\/Sicani-Anna-Rizzuti-la-ragazza-che-ha-prestato-il-suo-volto-per-la-locandina-della-sagra.jpg\",\"datePublished\":\"2024-03-11T12:26:44+00:00\",\"dateModified\":\"2025-02-24T12:29:38+00:00\",\"author\":{\"@id\":\"https:\/\/sicanivillages.com\/#\/schema\/person\/c11e3fc1b34e65666656600ff33eab56\"},\"breadcrumb\":{\"@id\":\"https:\/\/sicanivillages.com\/fr\/santangelo-muxaro-accueille-le-premier-festival-consacre-a-lasperge-sauvage-sicilienne\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/sicanivillages.com\/fr\/santangelo-muxaro-accueille-le-premier-festival-consacre-a-lasperge-sauvage-sicilienne\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/sicanivillages.com\/fr\/santangelo-muxaro-accueille-le-premier-festival-consacre-a-lasperge-sauvage-sicilienne\/#primaryimage\",\"url\":\"https:\/\/sicanivillages.com\/wp-content\/uploads\/2024\/03\/Sicani-Anna-Rizzuti-la-ragazza-che-ha-prestato-il-suo-volto-per-la-locandina-della-sagra.jpg\",\"contentUrl\":\"https:\/\/sicanivillages.com\/wp-content\/uploads\/2024\/03\/Sicani-Anna-Rizzuti-la-ragazza-che-ha-prestato-il-suo-volto-per-la-locandina-della-sagra.jpg\",\"width\":1534,\"height\":1227},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/sicanivillages.com\/fr\/santangelo-muxaro-accueille-le-premier-festival-consacre-a-lasperge-sauvage-sicilienne\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/sicanivillages.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sant&#8217;Angelo Muxaro accueille le premier festival consacr\u00e9 \u00e0 l&#8217;asperge sauvage sicilienne\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/sicanivillages.com\/#website\",\"url\":\"https:\/\/sicanivillages.com\/\",\"name\":\"SicaniVillages\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/sicanivillages.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/sicanivillages.com\/#\/schema\/person\/c11e3fc1b34e65666656600ff33eab56\",\"name\":\"Angela Mannino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/sicanivillages.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9ac7dc54465092a1ecdd15cb2d32d521c3830dccbff79d9d7835e7f7ce574eb6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9ac7dc54465092a1ecdd15cb2d32d521c3830dccbff79d9d7835e7f7ce574eb6?s=96&d=mm&r=g\",\"caption\":\"Angela Mannino\"},\"url\":\"https:\/\/sicanivillages.com\/fr\/author\/angela\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sant'Angelo Muxaro accueille le premier festival consacr\u00e9 \u00e0 l'asperge sauvage sicilienne - SicaniVillages","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sicanivillages.com\/fr\/santangelo-muxaro-accueille-le-premier-festival-consacre-a-lasperge-sauvage-sicilienne\/","og_locale":"fr_FR","og_type":"article","og_title":"Sant'Angelo Muxaro accueille le premier festival consacr\u00e9 \u00e0 l'asperge sauvage sicilienne - SicaniVillages","og_description":"Samedi 13 et dimanche 14 avril : grande f\u00eate avec spectacle, d\u00e9gustations culinaires et excursions.","og_url":"https:\/\/sicanivillages.com\/fr\/santangelo-muxaro-accueille-le-premier-festival-consacre-a-lasperge-sauvage-sicilienne\/","og_site_name":"SicaniVillages","article_published_time":"2024-03-11T12:26:44+00:00","article_modified_time":"2025-02-24T12:29:38+00:00","og_image":[{"width":1534,"height":1227,"url":"https:\/\/sicanivillages.com\/wp-content\/uploads\/2024\/03\/Sicani-Anna-Rizzuti-la-ragazza-che-ha-prestato-il-suo-volto-per-la-locandina-della-sagra.jpg","type":"image\/jpeg"}],"author":"Angela Mannino","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Angela Mannino","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sicanivillages.com\/fr\/santangelo-muxaro-accueille-le-premier-festival-consacre-a-lasperge-sauvage-sicilienne\/#article","isPartOf":{"@id":"https:\/\/sicanivillages.com\/fr\/santangelo-muxaro-accueille-le-premier-festival-consacre-a-lasperge-sauvage-sicilienne\/"},"author":{"name":"Angela Mannino","@id":"https:\/\/sicanivillages.com\/#\/schema\/person\/c11e3fc1b34e65666656600ff33eab56"},"headline":"Sant&rsquo;Angelo Muxaro accueille le premier festival consacr\u00e9 \u00e0 l&rsquo;asperge sauvage sicilienne","datePublished":"2024-03-11T12:26:44+00:00","dateModified":"2025-02-24T12:29:38+00:00","mainEntityOfPage":{"@id":"https:\/\/sicanivillages.com\/fr\/santangelo-muxaro-accueille-le-premier-festival-consacre-a-lasperge-sauvage-sicilienne\/"},"wordCount":1041,"image":{"@id":"https:\/\/sicanivillages.com\/fr\/santangelo-muxaro-accueille-le-premier-festival-consacre-a-lasperge-sauvage-sicilienne\/#primaryimage"},"thumbnailUrl":"https:\/\/sicanivillages.com\/wp-content\/uploads\/2024\/03\/Sicani-Anna-Rizzuti-la-ragazza-che-ha-prestato-il-suo-volto-per-la-locandina-della-sagra.jpg","articleSection":["Articles en vedette","Non classifi\u00e9(e)"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/sicanivillages.com\/fr\/santangelo-muxaro-accueille-le-premier-festival-consacre-a-lasperge-sauvage-sicilienne\/","url":"https:\/\/sicanivillages.com\/fr\/santangelo-muxaro-accueille-le-premier-festival-consacre-a-lasperge-sauvage-sicilienne\/","name":"Sant'Angelo Muxaro accueille le premier festival consacr\u00e9 \u00e0 l'asperge sauvage sicilienne - SicaniVillages","isPartOf":{"@id":"https:\/\/sicanivillages.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sicanivillages.com\/fr\/santangelo-muxaro-accueille-le-premier-festival-consacre-a-lasperge-sauvage-sicilienne\/#primaryimage"},"image":{"@id":"https:\/\/sicanivillages.com\/fr\/santangelo-muxaro-accueille-le-premier-festival-consacre-a-lasperge-sauvage-sicilienne\/#primaryimage"},"thumbnailUrl":"https:\/\/sicanivillages.com\/wp-content\/uploads\/2024\/03\/Sicani-Anna-Rizzuti-la-ragazza-che-ha-prestato-il-suo-volto-per-la-locandina-della-sagra.jpg","datePublished":"2024-03-11T12:26:44+00:00","dateModified":"2025-02-24T12:29:38+00:00","author":{"@id":"https:\/\/sicanivillages.com\/#\/schema\/person\/c11e3fc1b34e65666656600ff33eab56"},"breadcrumb":{"@id":"https:\/\/sicanivillages.com\/fr\/santangelo-muxaro-accueille-le-premier-festival-consacre-a-lasperge-sauvage-sicilienne\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sicanivillages.com\/fr\/santangelo-muxaro-accueille-le-premier-festival-consacre-a-lasperge-sauvage-sicilienne\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/sicanivillages.com\/fr\/santangelo-muxaro-accueille-le-premier-festival-consacre-a-lasperge-sauvage-sicilienne\/#primaryimage","url":"https:\/\/sicanivillages.com\/wp-content\/uploads\/2024\/03\/Sicani-Anna-Rizzuti-la-ragazza-che-ha-prestato-il-suo-volto-per-la-locandina-della-sagra.jpg","contentUrl":"https:\/\/sicanivillages.com\/wp-content\/uploads\/2024\/03\/Sicani-Anna-Rizzuti-la-ragazza-che-ha-prestato-il-suo-volto-per-la-locandina-della-sagra.jpg","width":1534,"height":1227},{"@type":"BreadcrumbList","@id":"https:\/\/sicanivillages.com\/fr\/santangelo-muxaro-accueille-le-premier-festival-consacre-a-lasperge-sauvage-sicilienne\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sicanivillages.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Sant&#8217;Angelo Muxaro accueille le premier festival consacr\u00e9 \u00e0 l&#8217;asperge sauvage sicilienne"}]},{"@type":"WebSite","@id":"https:\/\/sicanivillages.com\/#website","url":"https:\/\/sicanivillages.com\/","name":"SicaniVillages","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sicanivillages.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/sicanivillages.com\/#\/schema\/person\/c11e3fc1b34e65666656600ff33eab56","name":"Angela Mannino","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/sicanivillages.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/9ac7dc54465092a1ecdd15cb2d32d521c3830dccbff79d9d7835e7f7ce574eb6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9ac7dc54465092a1ecdd15cb2d32d521c3830dccbff79d9d7835e7f7ce574eb6?s=96&d=mm&r=g","caption":"Angela Mannino"},"url":"https:\/\/sicanivillages.com\/fr\/author\/angela\/"}]}},"_links":{"self":[{"href":"https:\/\/sicanivillages.com\/fr\/wp-json\/wp\/v2\/posts\/14906","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sicanivillages.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sicanivillages.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sicanivillages.com\/fr\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/sicanivillages.com\/fr\/wp-json\/wp\/v2\/comments?post=14906"}],"version-history":[{"count":9,"href":"https:\/\/sicanivillages.com\/fr\/wp-json\/wp\/v2\/posts\/14906\/revisions"}],"predecessor-version":[{"id":14957,"href":"https:\/\/sicanivillages.com\/fr\/wp-json\/wp\/v2\/posts\/14906\/revisions\/14957"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sicanivillages.com\/fr\/wp-json\/wp\/v2\/media\/12604"}],"wp:attachment":[{"href":"https:\/\/sicanivillages.com\/fr\/wp-json\/wp\/v2\/media?parent=14906"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sicanivillages.com\/fr\/wp-json\/wp\/v2\/categories?post=14906"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sicanivillages.com\/fr\/wp-json\/wp\/v2\/tags?post=14906"},{"taxonomy":"mese","embeddable":true,"href":"https:\/\/sicanivillages.com\/fr\/wp-json\/wp\/v2\/mese?post=14906"},{"taxonomy":"paese","embeddable":true,"href":"https:\/\/sicanivillages.com\/fr\/wp-json\/wp\/v2\/paese?post=14906"},{"taxonomy":"tipologia","embeddable":true,"href":"https:\/\/sicanivillages.com\/fr\/wp-json\/wp\/v2\/tipologia?post=14906"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}