{"id":14648,"date":"2023-12-15T11:10:05","date_gmt":"2023-12-15T11:10:05","guid":{"rendered":"https:\/\/sicanivillages.com\/la-professeure-de-mathematiques-qui-grace-a-la-terre-est-restee-dans-sa-sicile\/"},"modified":"2025-02-24T12:27:12","modified_gmt":"2025-02-24T12:27:12","slug":"la-professeure-de-mathematiques-qui-grace-a-la-terre-est-restee-dans-sa-sicile","status":"publish","type":"post","link":"https:\/\/sicanivillages.com\/fr\/la-professeure-de-mathematiques-qui-grace-a-la-terre-est-restee-dans-sa-sicile\/","title":{"rendered":"La professeure de math\u00e9matiques qui, gr\u00e2ce \u00e0 la terre, est rest\u00e9e dans sa Sicile"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"14648\" class=\"elementor elementor-14648 elementor-10713\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1743bb46 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1743bb46\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4fe7966\" data-id=\"4fe7966\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1c16676 elementor-widget elementor-widget-image\" data-id=\"1c16676\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.19.0 - 07-02-2024 *\/\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" width=\"1600\" height=\"833\" src=\"https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/12\/18-Foto1-Burgio-azienda-agricola-Riggio.webp\" class=\"elementor-animation-sink attachment-full size-full wp-image-10715\" alt=\"\" srcset=\"https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/12\/18-Foto1-Burgio-azienda-agricola-Riggio.webp 1600w, https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/12\/18-Foto1-Burgio-azienda-agricola-Riggio-300x156.webp 300w, https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/12\/18-Foto1-Burgio-azienda-agricola-Riggio-1024x533.webp 1024w, https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/12\/18-Foto1-Burgio-azienda-agricola-Riggio-768x400.webp 768w, https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/12\/18-Foto1-Burgio-azienda-agricola-Riggio-1536x800.webp 1536w, https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/12\/18-Foto1-Burgio-azienda-agricola-Riggio-600x312.webp 600w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-485115e elementor-widget elementor-widget-text-editor\" data-id=\"485115e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.19.0 - 07-02-2024 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t\n<h4>Le r\u00e9seau Sicani : les partenaires<\/h4>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-03a3392 elementor-widget elementor-widget-text-editor\" data-id=\"03a3392\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h1>La professeure de math\u00e9matiques qui, gr\u00e2ce \u00e0 la terre, est rest\u00e9e dans sa Sicile<\/h1>\n<div> <\/div>\n<div> <\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-13a95df5 elementor-widget elementor-widget-text-editor\" data-id=\"13a95df5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\n<h5>\u00c0 Burgio, l&rsquo;exploitation agricole Riggio<br>produit des oranges, des citrons et de l&rsquo;huile d&rsquo;evo.  <\/h5>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f35f526 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f35f526\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-52100c0\" data-id=\"52100c0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-762fe9a elementor-widget elementor-widget-text-editor\" data-id=\"762fe9a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\n<p>Au c\u0153ur de la Sicile, \u00e0 <strong>Burgio<\/strong>, village r\u00e9put\u00e9 pour ses c\u00e9ramiques et son ancienne fonderie o\u00f9 l&rsquo;on forge des cloches, la terre a une valeur inestimable pour Caterina Riggio, professeur de math\u00e9matiques et de physique au lyc\u00e9e de Bivona. Car c&rsquo;est gr\u00e2ce \u00e0 la terre, aux parcelles familiales, qu&rsquo;elle a pu rester dans sa Sicile natale, laissant de c\u00f4t\u00e9 l&rsquo;option de l&rsquo;\u00e9migration vers le Nord qui, pour beaucoup de jeunes Siciliens, semble \u00eatre la seule possibilit\u00e9 d&rsquo;entrer dans le monde du travail.<br>Aujourd&rsquo;hui, l<strong> &lsquo;exploitation agricole de Caterina Riggio<\/strong>, qui fait partie de la <strong>circonscription rurale de qualit\u00e9 des Sicani,<\/strong> s&rsquo;\u00e9tend sur quelque trente-six hectares et se consacre principalement \u00e0 la culture d&rsquo;olives, d&rsquo;oranges, de citrons et d&rsquo;amandes. Caterina l&rsquo;exploite avec son mari <strong>Stefano Ferrantelli.<\/strong><br>\u00ab\u00a0Lorsque nous nous sommes mari\u00e9s, raconte Caterina Riggio, notre situation professionnelle \u00e9tait encore pr\u00e9caire et si nous avons pu d\u00e9cider de rester \u00e0 Burgio, c&rsquo;est gr\u00e2ce \u00e0 la d\u00e9cision de nos parents de nous donner la terre qui nous a permis de d\u00e9marrer notre activit\u00e9. Pour nous, la terre est un tr\u00e9sor pr\u00e9cieux ; et c&rsquo;est sur le respect de la nature et la valorisation de l&rsquo;excellence du territoire que se fonde notre politique d&rsquo;entreprise, centr\u00e9e sur l&rsquo;authenticit\u00e9 de nos produits\u00a0\u00bb.  <\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a688a43 elementor-widget elementor-widget-image-carousel\" data-id=\"a688a43\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;none&quot;,&quot;autoplay&quot;:&quot;no&quot;,&quot;infinite&quot;:&quot;no&quot;,&quot;slides_to_show_mobile&quot;:&quot;1&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.19.0 - 07-02-2024 *\/\n.elementor-widget-image-carousel .swiper,.elementor-widget-image-carousel .swiper-container{position:static}.elementor-widget-image-carousel .swiper-container .swiper-slide figure,.elementor-widget-image-carousel .swiper .swiper-slide figure{line-height:inherit}.elementor-widget-image-carousel .swiper-slide{text-align:center}.elementor-image-carousel-wrapper:not(.swiper-container-initialized):not(.swiper-initialized) .swiper-slide{max-width:calc(100% \/ var(--e-image-carousel-slides-to-show, 3))}<\/style>\t\t<div class=\"elementor-image-carousel-wrapper swiper\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"polite\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 sur 1\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"a688a43\" data-elementor-lightbox-title=\"18 foto2 Burgio - azienda agricola Riggio\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTA3MTYsInVybCI6Imh0dHBzOlwvXC9zaWNhbml2aWxsYWdlcy5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjNcLzEyXC8xOC1mb3RvMi1CdXJnaW8tYXppZW5kYS1hZ3JpY29sYS1SaWdnaW8uanBnIiwic2xpZGVzaG93IjoiYTY4OGE0MyJ9\" href=\"https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/12\/18-foto2-Burgio-azienda-agricola-Riggio.jpg\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/12\/18-foto2-Burgio-azienda-agricola-Riggio-768x660.jpg\" alt=\"Azienda Agricola Riggio\" \/><figcaption class=\"elementor-image-carousel-caption\">Azienda Agricola Riggio<\/figcaption><\/figure><\/a><\/div>\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2046669 elementor-widget elementor-widget-text-editor\" data-id=\"2046669\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\n<p><strong>Les oranges Washington Navel et Vanilla ; les citrons de la vari\u00e9t\u00e9 Lunario,<\/strong> le citron qui ne cesse de fleurir et de fructifier tout au long de l&rsquo;ann\u00e9e ; l&rsquo;<strong>huile d&rsquo;olive extra vierge produite \u00e0 partir des cultivars Biancolilla, Nocellara et Passulunara ;<\/strong> et, enfin, les <strong>amandes<\/strong> typiques de la r\u00e9gion.<br>L&rsquo;exploitation agricole, explique Caterina Riggio, a commenc\u00e9 dans les ann\u00e9es 1940. Mon histoire commence avec mes grands-parents maternels, Caterina et Ciro Pinelli ; au d\u00e9but, ils ne poss\u00e9daient m\u00eame pas le terrain, ils le louaient \u00e0 de riches propri\u00e9taires terriens et mon grand-p\u00e8re l&rsquo;a choisi de mani\u00e8re \u00e0 ce qu&rsquo;il y ait une source d&rsquo;eau \u00e0 proximit\u00e9. C&rsquo;est ainsi que la culture des oranges a d\u00e9but\u00e9. Puis, dans les ann\u00e9es 1950, lorsque la prosp\u00e9rit\u00e9 \u00e9conomique a commenc\u00e9 \u00e0 s&rsquo;installer, mon grand-p\u00e8re a commenc\u00e9 \u00e0 acheter ses premi\u00e8res parcelles de terre. Il les a achet\u00e9es, puis revendues et en a achet\u00e9 d&rsquo;autres qui lui semblaient plus propices \u00e0 la culture des oranges, mieux expos\u00e9es ou avec plus d&rsquo;eau : l&rsquo;objectif \u00e9tait de produire les meilleures oranges possibles.<br>Une recherche de la qualit\u00e9 qui caract\u00e9rise toujours l&rsquo;exploitation Riggio. Dans notre famille, explique Caterina Riggio, nous avons toujours \u00e9t\u00e9 des travailleurs acharn\u00e9s et l&rsquo;amour de la terre a toujours \u00e9t\u00e9 une constante et une valeur \u00e0 transmettre. Lorsque vous vous mariez, vous recevez en cadeau un lopin de terre. Ainsi, dans les ann\u00e9es 1970, lorsque ma m\u00e8re s&rsquo;est mari\u00e9e, elle a re\u00e7u son propre lopin de terre. Une tradition que ma m\u00e8re Antonina et mon p\u00e8re Natale ont ensuite reproduite avec moi et ma s\u0153ur Rosalia\u00a0\u00bb. <br>En 2005, c&rsquo;est le tournant. Gr\u00e2ce \u00e0 un appel d&rsquo;offres r\u00e9gional visant \u00e0 promouvoir l&rsquo;entrepreneuriat agricole et \u00e0 son beau-p\u00e8re, ol\u00e9iculteur, qui lui loue ses terres, Caterina Riggio devient chef d&rsquo;entreprise et met d\u00e9finitivement de c\u00f4t\u00e9 l&rsquo;option nordique. <\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-23d9538 elementor-widget elementor-widget-image-carousel\" data-id=\"23d9538\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;none&quot;,&quot;autoplay&quot;:&quot;no&quot;,&quot;infinite&quot;:&quot;no&quot;,&quot;slides_to_show_mobile&quot;:&quot;1&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"polite\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 sur 1\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"23d9538\" data-elementor-lightbox-title=\"18 Foto1 Burgio - azienda agricola Riggio\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTA3MTcsInVybCI6Imh0dHBzOlwvXC9zaWNhbml2aWxsYWdlcy5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjNcLzEyXC8xOC1Gb3RvMS1CdXJnaW8tYXppZW5kYS1hZ3JpY29sYS1SaWdnaW8tMS53ZWJwIiwic2xpZGVzaG93IjoiMjNkOTUzOCJ9\" href=\"https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/12\/18-Foto1-Burgio-azienda-agricola-Riggio-1.webp\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/12\/18-Foto1-Burgio-azienda-agricola-Riggio-1-768x660.webp\" alt=\"Azienda Agricola Riggio - Burgio\" \/><figcaption class=\"elementor-image-carousel-caption\">Azienda Agricola Riggio - Burgio<\/figcaption><\/figure><\/a><\/div>\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fb2c882 elementor-widget elementor-widget-text-editor\" data-id=\"fb2c882\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\n<p>\u00ab\u00a0Aujourd&rsquo;hui, dit-il, nous esp\u00e9rons que notre choix pourra \u00e9galement \u00eatre suivi par nos filles : Claudia, quinze ans, qui fr\u00e9quente le lyc\u00e9e scientifique, et Flavia, neuf ans, qui est encore \u00e0 l&rsquo;\u00e9cole primaire. Notre terre nous a permis de ne pas \u00eatre contraints d&rsquo;\u00e9migrer dans les r\u00e9gions du nord de l&rsquo;Italie, et nous esp\u00e9rons que nos filles pourront elles aussi choisir librement de rester et de travailler l\u00e0 o\u00f9 elles sont n\u00e9es\u00a0\u00bb.<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3657843 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3657843\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-5bf56df\" data-id=\"5bf56df\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-45c2e42 elementor-widget elementor-widget-image\" data-id=\"45c2e42\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img width=\"100\" height=\"100\" src=\"https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/11\/redazione.png\" class=\"attachment-thumbnail size-thumbnail wp-image-10136\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-37adc50 elementor-widget elementor-widget-text-editor\" data-id=\"37adc50\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Texte des \u00e9diteurs<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-a3c9449\" data-id=\"a3c9449\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-78f8311\" data-id=\"78f8311\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-e753b67\" data-id=\"e753b67\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u00c0 Burgio, l&rsquo;exploitation agricole Riggio produit des oranges, des citrons et de l&rsquo;huile d&rsquo;evo.  <\/p>\n","protected":false},"author":4,"featured_media":12426,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","footnotes":""},"categories":[183,134],"tags":[],"mese":[],"paese":[],"tipologia":[],"class_list":["post-14648","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articles-en-vedette","category-non-classifiee"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La professeure de math\u00e9matiques qui, gr\u00e2ce \u00e0 la terre, est rest\u00e9e dans sa Sicile - SicaniVillages<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sicanivillages.com\/fr\/la-professeure-de-mathematiques-qui-grace-a-la-terre-est-restee-dans-sa-sicile\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La professeure de math\u00e9matiques qui, gr\u00e2ce \u00e0 la terre, est rest\u00e9e dans sa Sicile - SicaniVillages\" \/>\n<meta property=\"og:description\" content=\"\u00c0 Burgio, l&#039;exploitation agricole Riggio produit des oranges, des citrons et de l&#039;huile d&#039;evo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sicanivillages.com\/fr\/la-professeure-de-mathematiques-qui-grace-a-la-terre-est-restee-dans-sa-sicile\/\" \/>\n<meta property=\"og:site_name\" content=\"SicaniVillages\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-15T11:10:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-24T12:27:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/12\/18-Foto1-Burgio-azienda-agricola-Riggio.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"833\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/sicanivillages.com\/fr\/la-professeure-de-mathematiques-qui-grace-a-la-terre-est-restee-dans-sa-sicile\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/sicanivillages.com\/fr\/la-professeure-de-mathematiques-qui-grace-a-la-terre-est-restee-dans-sa-sicile\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\/\/sicanivillages.com\/#\/schema\/person\/0e21e04294f29467d1ed2340219cb5eb\"},\"headline\":\"La professeure de math\u00e9matiques qui, gr\u00e2ce \u00e0 la terre, est rest\u00e9e dans sa Sicile\",\"datePublished\":\"2023-12-15T11:10:05+00:00\",\"dateModified\":\"2025-02-24T12:27:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/sicanivillages.com\/fr\/la-professeure-de-mathematiques-qui-grace-a-la-terre-est-restee-dans-sa-sicile\/\"},\"wordCount\":712,\"image\":{\"@id\":\"https:\/\/sicanivillages.com\/fr\/la-professeure-de-mathematiques-qui-grace-a-la-terre-est-restee-dans-sa-sicile\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/12\/18-Foto1-Burgio-azienda-agricola-Riggio.webp\",\"articleSection\":[\"Articles en vedette\",\"Non classifi\u00e9(e)\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/sicanivillages.com\/fr\/la-professeure-de-mathematiques-qui-grace-a-la-terre-est-restee-dans-sa-sicile\/\",\"url\":\"https:\/\/sicanivillages.com\/fr\/la-professeure-de-mathematiques-qui-grace-a-la-terre-est-restee-dans-sa-sicile\/\",\"name\":\"La professeure de math\u00e9matiques qui, gr\u00e2ce \u00e0 la terre, est rest\u00e9e dans sa Sicile - SicaniVillages\",\"isPartOf\":{\"@id\":\"https:\/\/sicanivillages.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/sicanivillages.com\/fr\/la-professeure-de-mathematiques-qui-grace-a-la-terre-est-restee-dans-sa-sicile\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/sicanivillages.com\/fr\/la-professeure-de-mathematiques-qui-grace-a-la-terre-est-restee-dans-sa-sicile\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/12\/18-Foto1-Burgio-azienda-agricola-Riggio.webp\",\"datePublished\":\"2023-12-15T11:10:05+00:00\",\"dateModified\":\"2025-02-24T12:27:12+00:00\",\"author\":{\"@id\":\"https:\/\/sicanivillages.com\/#\/schema\/person\/0e21e04294f29467d1ed2340219cb5eb\"},\"breadcrumb\":{\"@id\":\"https:\/\/sicanivillages.com\/fr\/la-professeure-de-mathematiques-qui-grace-a-la-terre-est-restee-dans-sa-sicile\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/sicanivillages.com\/fr\/la-professeure-de-mathematiques-qui-grace-a-la-terre-est-restee-dans-sa-sicile\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/sicanivillages.com\/fr\/la-professeure-de-mathematiques-qui-grace-a-la-terre-est-restee-dans-sa-sicile\/#primaryimage\",\"url\":\"https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/12\/18-Foto1-Burgio-azienda-agricola-Riggio.webp\",\"contentUrl\":\"https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/12\/18-Foto1-Burgio-azienda-agricola-Riggio.webp\",\"width\":1600,\"height\":833},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/sicanivillages.com\/fr\/la-professeure-de-mathematiques-qui-grace-a-la-terre-est-restee-dans-sa-sicile\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/sicanivillages.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La professeure de math\u00e9matiques qui, gr\u00e2ce \u00e0 la terre, est rest\u00e9e dans sa Sicile\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/sicanivillages.com\/#website\",\"url\":\"https:\/\/sicanivillages.com\/\",\"name\":\"SicaniVillages\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/sicanivillages.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/sicanivillages.com\/#\/schema\/person\/0e21e04294f29467d1ed2340219cb5eb\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/sicanivillages.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c8879fbd1a1b23ce6e384dc15d3f74c42237fbcedd0e0753c04d3103a5a3db4c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c8879fbd1a1b23ce6e384dc15d3f74c42237fbcedd0e0753c04d3103a5a3db4c?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\/\/sicanivillages.com\/fr\/author\/sicanivillages\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La professeure de math\u00e9matiques qui, gr\u00e2ce \u00e0 la terre, est rest\u00e9e dans sa Sicile - SicaniVillages","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sicanivillages.com\/fr\/la-professeure-de-mathematiques-qui-grace-a-la-terre-est-restee-dans-sa-sicile\/","og_locale":"fr_FR","og_type":"article","og_title":"La professeure de math\u00e9matiques qui, gr\u00e2ce \u00e0 la terre, est rest\u00e9e dans sa Sicile - SicaniVillages","og_description":"\u00c0 Burgio, l'exploitation agricole Riggio produit des oranges, des citrons et de l'huile d'evo.","og_url":"https:\/\/sicanivillages.com\/fr\/la-professeure-de-mathematiques-qui-grace-a-la-terre-est-restee-dans-sa-sicile\/","og_site_name":"SicaniVillages","article_published_time":"2023-12-15T11:10:05+00:00","article_modified_time":"2025-02-24T12:27:12+00:00","og_image":[{"width":1600,"height":833,"url":"https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/12\/18-Foto1-Burgio-azienda-agricola-Riggio.webp","type":"image\/webp"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Redazione","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sicanivillages.com\/fr\/la-professeure-de-mathematiques-qui-grace-a-la-terre-est-restee-dans-sa-sicile\/#article","isPartOf":{"@id":"https:\/\/sicanivillages.com\/fr\/la-professeure-de-mathematiques-qui-grace-a-la-terre-est-restee-dans-sa-sicile\/"},"author":{"name":"Redazione","@id":"https:\/\/sicanivillages.com\/#\/schema\/person\/0e21e04294f29467d1ed2340219cb5eb"},"headline":"La professeure de math\u00e9matiques qui, gr\u00e2ce \u00e0 la terre, est rest\u00e9e dans sa Sicile","datePublished":"2023-12-15T11:10:05+00:00","dateModified":"2025-02-24T12:27:12+00:00","mainEntityOfPage":{"@id":"https:\/\/sicanivillages.com\/fr\/la-professeure-de-mathematiques-qui-grace-a-la-terre-est-restee-dans-sa-sicile\/"},"wordCount":712,"image":{"@id":"https:\/\/sicanivillages.com\/fr\/la-professeure-de-mathematiques-qui-grace-a-la-terre-est-restee-dans-sa-sicile\/#primaryimage"},"thumbnailUrl":"https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/12\/18-Foto1-Burgio-azienda-agricola-Riggio.webp","articleSection":["Articles en vedette","Non classifi\u00e9(e)"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/sicanivillages.com\/fr\/la-professeure-de-mathematiques-qui-grace-a-la-terre-est-restee-dans-sa-sicile\/","url":"https:\/\/sicanivillages.com\/fr\/la-professeure-de-mathematiques-qui-grace-a-la-terre-est-restee-dans-sa-sicile\/","name":"La professeure de math\u00e9matiques qui, gr\u00e2ce \u00e0 la terre, est rest\u00e9e dans sa Sicile - SicaniVillages","isPartOf":{"@id":"https:\/\/sicanivillages.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sicanivillages.com\/fr\/la-professeure-de-mathematiques-qui-grace-a-la-terre-est-restee-dans-sa-sicile\/#primaryimage"},"image":{"@id":"https:\/\/sicanivillages.com\/fr\/la-professeure-de-mathematiques-qui-grace-a-la-terre-est-restee-dans-sa-sicile\/#primaryimage"},"thumbnailUrl":"https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/12\/18-Foto1-Burgio-azienda-agricola-Riggio.webp","datePublished":"2023-12-15T11:10:05+00:00","dateModified":"2025-02-24T12:27:12+00:00","author":{"@id":"https:\/\/sicanivillages.com\/#\/schema\/person\/0e21e04294f29467d1ed2340219cb5eb"},"breadcrumb":{"@id":"https:\/\/sicanivillages.com\/fr\/la-professeure-de-mathematiques-qui-grace-a-la-terre-est-restee-dans-sa-sicile\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sicanivillages.com\/fr\/la-professeure-de-mathematiques-qui-grace-a-la-terre-est-restee-dans-sa-sicile\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/sicanivillages.com\/fr\/la-professeure-de-mathematiques-qui-grace-a-la-terre-est-restee-dans-sa-sicile\/#primaryimage","url":"https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/12\/18-Foto1-Burgio-azienda-agricola-Riggio.webp","contentUrl":"https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/12\/18-Foto1-Burgio-azienda-agricola-Riggio.webp","width":1600,"height":833},{"@type":"BreadcrumbList","@id":"https:\/\/sicanivillages.com\/fr\/la-professeure-de-mathematiques-qui-grace-a-la-terre-est-restee-dans-sa-sicile\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sicanivillages.com\/fr\/"},{"@type":"ListItem","position":2,"name":"La professeure de math\u00e9matiques qui, gr\u00e2ce \u00e0 la terre, est rest\u00e9e dans sa Sicile"}]},{"@type":"WebSite","@id":"https:\/\/sicanivillages.com\/#website","url":"https:\/\/sicanivillages.com\/","name":"SicaniVillages","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sicanivillages.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/sicanivillages.com\/#\/schema\/person\/0e21e04294f29467d1ed2340219cb5eb","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/sicanivillages.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c8879fbd1a1b23ce6e384dc15d3f74c42237fbcedd0e0753c04d3103a5a3db4c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c8879fbd1a1b23ce6e384dc15d3f74c42237fbcedd0e0753c04d3103a5a3db4c?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/sicanivillages.com\/fr\/author\/sicanivillages\/"}]}},"_links":{"self":[{"href":"https:\/\/sicanivillages.com\/fr\/wp-json\/wp\/v2\/posts\/14648","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sicanivillages.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sicanivillages.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sicanivillages.com\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/sicanivillages.com\/fr\/wp-json\/wp\/v2\/comments?post=14648"}],"version-history":[{"count":11,"href":"https:\/\/sicanivillages.com\/fr\/wp-json\/wp\/v2\/posts\/14648\/revisions"}],"predecessor-version":[{"id":14712,"href":"https:\/\/sicanivillages.com\/fr\/wp-json\/wp\/v2\/posts\/14648\/revisions\/14712"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sicanivillages.com\/fr\/wp-json\/wp\/v2\/media\/12426"}],"wp:attachment":[{"href":"https:\/\/sicanivillages.com\/fr\/wp-json\/wp\/v2\/media?parent=14648"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sicanivillages.com\/fr\/wp-json\/wp\/v2\/categories?post=14648"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sicanivillages.com\/fr\/wp-json\/wp\/v2\/tags?post=14648"},{"taxonomy":"mese","embeddable":true,"href":"https:\/\/sicanivillages.com\/fr\/wp-json\/wp\/v2\/mese?post=14648"},{"taxonomy":"paese","embeddable":true,"href":"https:\/\/sicanivillages.com\/fr\/wp-json\/wp\/v2\/paese?post=14648"},{"taxonomy":"tipologia","embeddable":true,"href":"https:\/\/sicanivillages.com\/fr\/wp-json\/wp\/v2\/tipologia?post=14648"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}