{"id":14587,"date":"2023-11-25T15:05:53","date_gmt":"2023-11-25T15:05:53","guid":{"rendered":"https:\/\/sicanivillages.com\/le-reve-dun-revenant-sicilien-se-realise-dans-lentreprise-familiale\/"},"modified":"2025-02-24T12:26:36","modified_gmt":"2025-02-24T12:26:36","slug":"le-reve-dun-revenant-sicilien-se-realise-dans-lentreprise-familiale","status":"publish","type":"post","link":"https:\/\/sicanivillages.com\/fr\/le-reve-dun-revenant-sicilien-se-realise-dans-lentreprise-familiale\/","title":{"rendered":"Le r\u00eave d&rsquo;un revenant sicilien se r\u00e9alise dans l&rsquo;entreprise familiale"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"14587\" class=\"elementor elementor-14587 elementor-10277\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1743bb46 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1743bb46\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4fe7966\" data-id=\"4fe7966\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1c16676 elementor-widget elementor-widget-image\" data-id=\"1c16676\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.19.0 - 07-02-2024 *\/\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" width=\"2560\" height=\"1707\" src=\"https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/11\/Giangiuffre-3-scaled.jpeg\" class=\"elementor-animation-sink attachment-full size-full wp-image-10280\" alt=\"\" srcset=\"https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/11\/Giangiuffre-3-scaled.jpeg 2560w, https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/11\/Giangiuffre-3-300x200.jpeg 300w, https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/11\/Giangiuffre-3-1024x683.jpeg 1024w, https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/11\/Giangiuffre-3-768x512.jpeg 768w, https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/11\/Giangiuffre-3-1536x1024.jpeg 1536w, https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/11\/Giangiuffre-3-2048x1365.jpeg 2048w, https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/11\/Giangiuffre-3-600x400.jpeg 600w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-485115e elementor-widget elementor-widget-text-editor\" data-id=\"485115e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.19.0 - 07-02-2024 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t\n<h4>Le r\u00e9seau Sicani : les partenaires<\/h4>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-03a3392 elementor-widget elementor-widget-text-editor\" data-id=\"03a3392\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h1>Dans l&rsquo;entreprise familiale se r\u00e9alise <br>le r\u00eave d&rsquo;un rapatri\u00e9 sicilien<\/h1>\n<div> <\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-a607276 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a607276\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-38e71f0\" data-id=\"38e71f0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-710bd6a\" data-id=\"710bd6a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-13a95df5 elementor-widget elementor-widget-text-editor\" data-id=\"13a95df5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\n<h5>\u00c0 Cammarata, entre nature et go\u00fbt, \u00e0 l&rsquo;Antica Masseria Gargiuff\u00e8<\/h5>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f35f526 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f35f526\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-52100c0\" data-id=\"52100c0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-762fe9a elementor-widget elementor-widget-text-editor\" data-id=\"762fe9a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\n<p>Celle de l&rsquo;Antica Masseria Gargiuff\u00e8, dans la r\u00e9gion de <strong>Cammarata<\/strong>, est une histoire qui commence \u00e0 <strong>Santo Stefano Quisquina<\/strong>, se d\u00e9place sur les pentes du V\u00e9suve, s&rsquo;envole de l&rsquo;autre c\u00f4t\u00e9 de l&rsquo;Atlantique puis du d\u00e9troit de Sicile, touche l&rsquo;Italie du Nord, pour revenir sur l&rsquo;\u00eele avec un bagage charg\u00e9 d&rsquo;exp\u00e9riences et de r\u00eaves \u00e0 r\u00e9aliser.<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a688a43 elementor-widget elementor-widget-image-carousel\" data-id=\"a688a43\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;2&quot;,&quot;slides_to_scroll&quot;:&quot;2&quot;,&quot;navigation&quot;:&quot;none&quot;,&quot;autoplay&quot;:&quot;no&quot;,&quot;infinite&quot;:&quot;no&quot;,&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:15,&quot;sizes&quot;:[]},&quot;slides_to_show_mobile&quot;:&quot;2&quot;,&quot;slides_to_scroll_mobile&quot;:&quot;2&quot;,&quot;speed&quot;:500,&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.19.0 - 07-02-2024 *\/\n.elementor-widget-image-carousel .swiper,.elementor-widget-image-carousel .swiper-container{position:static}.elementor-widget-image-carousel .swiper-container .swiper-slide figure,.elementor-widget-image-carousel .swiper .swiper-slide figure{line-height:inherit}.elementor-widget-image-carousel .swiper-slide{text-align:center}.elementor-image-carousel-wrapper:not(.swiper-container-initialized):not(.swiper-initialized) .swiper-slide{max-width:calc(100% \/ var(--e-image-carousel-slides-to-show, 3))}<\/style>\t\t<div class=\"elementor-image-carousel-wrapper swiper\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"polite\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 sur 2\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"a688a43\" data-elementor-lightbox-title=\"Giangiuffr\u00e8 2\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTAyODIsInVybCI6Imh0dHBzOlwvXC9zaWNhbml2aWxsYWdlcy5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjNcLzExXC9HaWFuZ2l1ZmZyZS0yLmpwZWciLCJzbGlkZXNob3ciOiJhNjg4YTQzIn0%3D\" href=\"https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/11\/Giangiuffre-2.jpeg\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/11\/Giangiuffre-2-768x660.jpeg\" alt=\"Giangiuffr\u00e8 2\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 sur 2\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"a688a43\" data-elementor-lightbox-title=\"Giangiuffr\u00e8 6\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTAyODMsInVybCI6Imh0dHBzOlwvXC9zaWNhbml2aWxsYWdlcy5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjNcLzExXC9HaWFuZ2l1ZmZyZS02LmpwZWciLCJzbGlkZXNob3ciOiJhNjg4YTQzIn0%3D\" href=\"https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/11\/Giangiuffre-6.jpeg\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/11\/Giangiuffre-6-768x660.jpeg\" alt=\"Giangiuffr\u00e8 6\" \/><\/figure><\/a><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2046669 elementor-widget elementor-widget-text-editor\" data-id=\"2046669\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\n<p>Voil\u00e0, en quelques mots, le parcours de <strong>Cristina Rosalia Massaro Cenere<\/strong>, 32 ans, experte en relations internationales avec un dipl\u00f4me en langues orientales, obtenu \u00e0 Naples, un stage \u00e0 New York aux Nations unies, quatre mois pass\u00e9s \u00e0 Tunis et un an de travail \u00e0 Milan dans une multinationale. Puis, en 2017, c&rsquo;est le tournant.<br><em>\u00ab\u00a0L&rsquo;entr\u00e9e<\/em>, raconte Cristina, a \u00e9t\u00e9 l&rsquo;appel \u00e0 candidatures europ\u00e9en qui est sorti cette ann\u00e9e-l\u00e0 et qui \u00e9tait d\u00e9di\u00e9 aux jeunes entrepreneurs. Je me suis dit que c&rsquo;\u00e9tait la bonne occasion de me remettre dans le bain et de revenir sur mes terres&rsquo;. Dans le silence et la nature intacte des monts Sicani, \u00e0 un quart d&rsquo;heure de l&rsquo;ermitage de Santa Rosalia alla Quisquina, \u00e0 proximit\u00e9 du suggestif th\u00e9\u00e2tre Androm\u00e8de, dans une zone riche en sentiers naturels. Bref, rien \u00e0 voir avec l&rsquo;air que l&rsquo;on respire dans la ville milanaise et son rythme effr\u00e9n\u00e9.    <\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-23d9538 elementor-widget elementor-widget-image-carousel\" data-id=\"23d9538\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;2&quot;,&quot;slides_to_scroll&quot;:&quot;2&quot;,&quot;navigation&quot;:&quot;none&quot;,&quot;autoplay&quot;:&quot;no&quot;,&quot;infinite&quot;:&quot;no&quot;,&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:15,&quot;sizes&quot;:[]},&quot;slides_to_show_mobile&quot;:&quot;2&quot;,&quot;slides_to_scroll_mobile&quot;:&quot;2&quot;,&quot;speed&quot;:500,&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"polite\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 sur 2\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"23d9538\" data-elementor-lightbox-title=\"Giangiuffr\u00e8 5\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTAyODUsInVybCI6Imh0dHBzOlwvXC9zaWNhbml2aWxsYWdlcy5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjNcLzExXC9HaWFuZ2l1ZmZyZS01LXNjYWxlZC5qcGVnIiwic2xpZGVzaG93IjoiMjNkOTUzOCJ9\" href=\"https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/11\/Giangiuffre-5-scaled.jpeg\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/11\/Giangiuffre-5-768x660.jpeg\" alt=\"Giangiuffr\u00e8 5\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 sur 2\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"23d9538\" data-elementor-lightbox-title=\"Giangiuffr\u00e8 4\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTAyODQsInVybCI6Imh0dHBzOlwvXC9zaWNhbml2aWxsYWdlcy5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjNcLzExXC9HaWFuZ2l1ZmZyZS00LmpwZWciLCJzbGlkZXNob3ciOiIyM2Q5NTM4In0%3D\" href=\"https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/11\/Giangiuffre-4.jpeg\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/11\/Giangiuffre-4-768x660.jpeg\" alt=\"Giangiuffr\u00e8 4\" \/><\/figure><\/a><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fb2c882 elementor-widget elementor-widget-text-editor\" data-id=\"fb2c882\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\n<p><strong>L&rsquo;exploitation agricole et l&rsquo;agritourisme Antica Masseria Gargiuff\u00e8<\/strong>, du nom de la commune o\u00f9 elle se trouve, fait partie du <strong>district de qualit\u00e9 rurale Sicani<\/strong> et, en raison de sa situation particuli\u00e8re et de la qualit\u00e9 de sa cuisine, a re\u00e7u la <strong>marque de la ruralit\u00e9 m\u00e9diterran\u00e9enne<\/strong>. Son histoire commence \u00e0 la fin du XIXe si\u00e8cle avec Antonino Massaro, l&rsquo;arri\u00e8re-grand-p\u00e8re de Cristina. Ce domaine de 130 hectares, situ\u00e9 au c\u0153ur de la zone naturelle du Monte Cammarata, est facilement accessible en empruntant la route provinciale qui relie Santo Stefano Quisquina, le village d&rsquo;origine de la famille, \u00e0 Cammarata. <br>\u00ab\u00a0En 1981, raconte Cristina Rosalia Massaro Cenere, aujourd&rsquo;hui propri\u00e9taire unique de l&rsquo;Antica Masseria Gargiuff\u00e8, le flambeau a \u00e9t\u00e9 transmis \u00e0 mon p\u00e8re Francesco, qui en a fait la premi\u00e8re ferme de la r\u00e9gion dot\u00e9e d&rsquo;\u00e9tables m\u00e9canis\u00e9es : l&rsquo;\u00e9levage de bovins et d&rsquo;ovins \u00e9tait en effet destin\u00e9 \u00e0 la production de lait et de fromage. En 2000, \u00e0 l&#8217;emplacement de l&rsquo;ancienne ferme, ont commenc\u00e9 les travaux de construction de l&rsquo;h\u00f4tel, qui compte aujourd&rsquo;hui vingt-cinq lits, et du restaurant\u00a0\u00bb.  <\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8c1bdea elementor-widget elementor-widget-image-carousel\" data-id=\"8c1bdea\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;2&quot;,&quot;slides_to_scroll&quot;:&quot;2&quot;,&quot;navigation&quot;:&quot;none&quot;,&quot;autoplay&quot;:&quot;no&quot;,&quot;infinite&quot;:&quot;no&quot;,&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:15,&quot;sizes&quot;:[]},&quot;slides_to_show_mobile&quot;:&quot;2&quot;,&quot;slides_to_scroll_mobile&quot;:&quot;2&quot;,&quot;speed&quot;:500,&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"polite\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 sur 2\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"8c1bdea\" data-elementor-lightbox-title=\"Giangiuffr\u00e8 3\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTAyODcsInVybCI6Imh0dHBzOlwvXC9zaWNhbml2aWxsYWdlcy5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjNcLzExXC9HaWFuZ2l1ZmZyZS0zLTEtc2NhbGVkLmpwZWciLCJzbGlkZXNob3ciOiI4YzFiZGVhIn0%3D\" href=\"https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/11\/Giangiuffre-3-1-scaled.jpeg\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/11\/Giangiuffre-3-1-768x660.jpeg\" alt=\"Giangiuffr\u00e8 3\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 sur 2\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"8c1bdea\" data-elementor-lightbox-title=\"Giangiuffr\u00e8 1\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTAyODgsInVybCI6Imh0dHBzOlwvXC9zaWNhbml2aWxsYWdlcy5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjNcLzExXC9HaWFuZ2l1ZmZyZS0xLmpwZWciLCJzbGlkZXNob3ciOiI4YzFiZGVhIn0%3D\" href=\"https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/11\/Giangiuffre-1.jpeg\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/11\/Giangiuffre-1-768x660.jpeg\" alt=\"Giangiuffr\u00e8 1\" \/><\/figure><\/a><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dc00575 elementor-widget elementor-widget-text-editor\" data-id=\"dc00575\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\n<p>Aujourd&rsquo;hui, l&rsquo;agrotourisme est l&rsquo;activit\u00e9 principale. \u00ab\u00a0Notre client\u00e8le est essentiellement locale, mais les Suisses, les Allemands et les Autrichiens viennent aussi. Quoi qu&rsquo;il en soit, tous recherchent la tranquillit\u00e9 et les plats traditionnels. Le tout \u00e0 base de produits locaux authentiques. Parmi les produits phares de la carte, toujours attentive \u00e0 la saisonnalit\u00e9, on trouve le rotolone di cotenna farci de fromage de brebis, de persil et d&rsquo;oignons et cuisin\u00e9 \u00e0 la sauce tomate, les pappardelle au rago\u00fbt de sanglier et l&rsquo;agneau, le porc et le veau produits dans l&rsquo;exploitation.   <br>Parmi nos activit\u00e9s, explique Cristina Rosalia Massaro Cenere, il y a aussi la production d&rsquo;origan, pour laquelle nous avons cr\u00e9\u00e9 un atelier de transformation sp\u00e9cial, et la production des fruits de l&rsquo;amour, des baies qui ressemblent \u00e0 l&rsquo;\u00e9glantine et que nous exportons en Hollande. Bient\u00f4t, nous pr\u00e9voyons \u00e9galement d&rsquo;ouvrir une salle de d\u00e9gustation qui sera consacr\u00e9e \u00e0 la production de confitures et de miel de rose\u00a0\u00bb.<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e07d159 elementor-widget elementor-widget-image-carousel\" data-id=\"e07d159\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;2&quot;,&quot;slides_to_scroll&quot;:&quot;2&quot;,&quot;navigation&quot;:&quot;none&quot;,&quot;autoplay&quot;:&quot;no&quot;,&quot;infinite&quot;:&quot;no&quot;,&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:15,&quot;sizes&quot;:[]},&quot;slides_to_show_mobile&quot;:&quot;2&quot;,&quot;slides_to_scroll_mobile&quot;:&quot;2&quot;,&quot;speed&quot;:500,&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"polite\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 sur 2\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"e07d159\" data-elementor-lightbox-title=\"Giangiuffr\u00e8 8\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTAyODksInVybCI6Imh0dHBzOlwvXC9zaWNhbml2aWxsYWdlcy5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjNcLzExXC9HaWFuZ2l1ZmZyZS04LmpwZWciLCJzbGlkZXNob3ciOiJlMDdkMTU5In0%3D\" href=\"https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/11\/Giangiuffre-8.jpeg\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/11\/Giangiuffre-8-768x660.jpeg\" alt=\"Giangiuffr\u00e8 8\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 sur 2\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"e07d159\" data-elementor-lightbox-title=\"Giangiuffr\u00e8 7\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTAyOTAsInVybCI6Imh0dHBzOlwvXC9zaWNhbml2aWxsYWdlcy5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjNcLzExXC9HaWFuZ2l1ZmZyZS03LmpwZWciLCJzbGlkZXNob3ciOiJlMDdkMTU5In0%3D\" href=\"https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/11\/Giangiuffre-7.jpeg\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/11\/Giangiuffre-7-768x617.jpeg\" alt=\"Giangiuffr\u00e8 7\" \/><\/figure><\/a><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3657843 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3657843\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-5bf56df\" data-id=\"5bf56df\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-45c2e42 elementor-widget elementor-widget-image\" data-id=\"45c2e42\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img width=\"100\" height=\"100\" src=\"https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/11\/redazione.png\" class=\"attachment-thumbnail size-thumbnail wp-image-10136\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-37adc50 elementor-widget elementor-widget-text-editor\" data-id=\"37adc50\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Texte des \u00e9diteurs<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-a3c9449\" data-id=\"a3c9449\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-78f8311\" data-id=\"78f8311\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-e753b67\" data-id=\"e753b67\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u00c0 Cammarata, entre nature et go\u00fbt, \u00e0 l&rsquo;Antica Masseria Gargiuff\u00e8<\/p>\n","protected":false},"author":4,"featured_media":12374,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","footnotes":""},"categories":[183,134],"tags":[],"mese":[],"paese":[],"tipologia":[],"class_list":["post-14587","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articles-en-vedette","category-non-classifiee"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Le r\u00eave d&#039;un revenant sicilien se r\u00e9alise dans l&#039;entreprise familiale - SicaniVillages<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sicanivillages.com\/fr\/le-reve-dun-revenant-sicilien-se-realise-dans-lentreprise-familiale\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le r\u00eave d&#039;un revenant sicilien se r\u00e9alise dans l&#039;entreprise familiale - SicaniVillages\" \/>\n<meta property=\"og:description\" content=\"\u00c0 Cammarata, entre nature et go\u00fbt, \u00e0 l&#039;Antica Masseria Gargiuff\u00e8\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sicanivillages.com\/fr\/le-reve-dun-revenant-sicilien-se-realise-dans-lentreprise-familiale\/\" \/>\n<meta property=\"og:site_name\" content=\"SicaniVillages\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-25T15:05:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-24T12:26:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/11\/Giangiuffre-3-scaled.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/sicanivillages.com\/fr\/le-reve-dun-revenant-sicilien-se-realise-dans-lentreprise-familiale\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/sicanivillages.com\/fr\/le-reve-dun-revenant-sicilien-se-realise-dans-lentreprise-familiale\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\/\/sicanivillages.com\/#\/schema\/person\/0e21e04294f29467d1ed2340219cb5eb\"},\"headline\":\"Le r\u00eave d&rsquo;un revenant sicilien se r\u00e9alise dans l&rsquo;entreprise familiale\",\"datePublished\":\"2023-11-25T15:05:53+00:00\",\"dateModified\":\"2025-02-24T12:26:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/sicanivillages.com\/fr\/le-reve-dun-revenant-sicilien-se-realise-dans-lentreprise-familiale\/\"},\"wordCount\":633,\"image\":{\"@id\":\"https:\/\/sicanivillages.com\/fr\/le-reve-dun-revenant-sicilien-se-realise-dans-lentreprise-familiale\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/11\/Giangiuffre-3-scaled.jpeg\",\"articleSection\":[\"Articles en vedette\",\"Non classifi\u00e9(e)\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/sicanivillages.com\/fr\/le-reve-dun-revenant-sicilien-se-realise-dans-lentreprise-familiale\/\",\"url\":\"https:\/\/sicanivillages.com\/fr\/le-reve-dun-revenant-sicilien-se-realise-dans-lentreprise-familiale\/\",\"name\":\"Le r\u00eave d'un revenant sicilien se r\u00e9alise dans l'entreprise familiale - SicaniVillages\",\"isPartOf\":{\"@id\":\"https:\/\/sicanivillages.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/sicanivillages.com\/fr\/le-reve-dun-revenant-sicilien-se-realise-dans-lentreprise-familiale\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/sicanivillages.com\/fr\/le-reve-dun-revenant-sicilien-se-realise-dans-lentreprise-familiale\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/11\/Giangiuffre-3-scaled.jpeg\",\"datePublished\":\"2023-11-25T15:05:53+00:00\",\"dateModified\":\"2025-02-24T12:26:36+00:00\",\"author\":{\"@id\":\"https:\/\/sicanivillages.com\/#\/schema\/person\/0e21e04294f29467d1ed2340219cb5eb\"},\"breadcrumb\":{\"@id\":\"https:\/\/sicanivillages.com\/fr\/le-reve-dun-revenant-sicilien-se-realise-dans-lentreprise-familiale\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/sicanivillages.com\/fr\/le-reve-dun-revenant-sicilien-se-realise-dans-lentreprise-familiale\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/sicanivillages.com\/fr\/le-reve-dun-revenant-sicilien-se-realise-dans-lentreprise-familiale\/#primaryimage\",\"url\":\"https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/11\/Giangiuffre-3-scaled.jpeg\",\"contentUrl\":\"https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/11\/Giangiuffre-3-scaled.jpeg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/sicanivillages.com\/fr\/le-reve-dun-revenant-sicilien-se-realise-dans-lentreprise-familiale\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/sicanivillages.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le r\u00eave d&rsquo;un revenant sicilien se r\u00e9alise dans l&rsquo;entreprise familiale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/sicanivillages.com\/#website\",\"url\":\"https:\/\/sicanivillages.com\/\",\"name\":\"SicaniVillages\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/sicanivillages.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/sicanivillages.com\/#\/schema\/person\/0e21e04294f29467d1ed2340219cb5eb\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/sicanivillages.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c8879fbd1a1b23ce6e384dc15d3f74c42237fbcedd0e0753c04d3103a5a3db4c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c8879fbd1a1b23ce6e384dc15d3f74c42237fbcedd0e0753c04d3103a5a3db4c?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\/\/sicanivillages.com\/fr\/author\/sicanivillages\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le r\u00eave d'un revenant sicilien se r\u00e9alise dans l'entreprise familiale - SicaniVillages","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sicanivillages.com\/fr\/le-reve-dun-revenant-sicilien-se-realise-dans-lentreprise-familiale\/","og_locale":"fr_FR","og_type":"article","og_title":"Le r\u00eave d'un revenant sicilien se r\u00e9alise dans l'entreprise familiale - SicaniVillages","og_description":"\u00c0 Cammarata, entre nature et go\u00fbt, \u00e0 l'Antica Masseria Gargiuff\u00e8","og_url":"https:\/\/sicanivillages.com\/fr\/le-reve-dun-revenant-sicilien-se-realise-dans-lentreprise-familiale\/","og_site_name":"SicaniVillages","article_published_time":"2023-11-25T15:05:53+00:00","article_modified_time":"2025-02-24T12:26:36+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/11\/Giangiuffre-3-scaled.jpeg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Redazione","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sicanivillages.com\/fr\/le-reve-dun-revenant-sicilien-se-realise-dans-lentreprise-familiale\/#article","isPartOf":{"@id":"https:\/\/sicanivillages.com\/fr\/le-reve-dun-revenant-sicilien-se-realise-dans-lentreprise-familiale\/"},"author":{"name":"Redazione","@id":"https:\/\/sicanivillages.com\/#\/schema\/person\/0e21e04294f29467d1ed2340219cb5eb"},"headline":"Le r\u00eave d&rsquo;un revenant sicilien se r\u00e9alise dans l&rsquo;entreprise familiale","datePublished":"2023-11-25T15:05:53+00:00","dateModified":"2025-02-24T12:26:36+00:00","mainEntityOfPage":{"@id":"https:\/\/sicanivillages.com\/fr\/le-reve-dun-revenant-sicilien-se-realise-dans-lentreprise-familiale\/"},"wordCount":633,"image":{"@id":"https:\/\/sicanivillages.com\/fr\/le-reve-dun-revenant-sicilien-se-realise-dans-lentreprise-familiale\/#primaryimage"},"thumbnailUrl":"https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/11\/Giangiuffre-3-scaled.jpeg","articleSection":["Articles en vedette","Non classifi\u00e9(e)"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/sicanivillages.com\/fr\/le-reve-dun-revenant-sicilien-se-realise-dans-lentreprise-familiale\/","url":"https:\/\/sicanivillages.com\/fr\/le-reve-dun-revenant-sicilien-se-realise-dans-lentreprise-familiale\/","name":"Le r\u00eave d'un revenant sicilien se r\u00e9alise dans l'entreprise familiale - SicaniVillages","isPartOf":{"@id":"https:\/\/sicanivillages.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sicanivillages.com\/fr\/le-reve-dun-revenant-sicilien-se-realise-dans-lentreprise-familiale\/#primaryimage"},"image":{"@id":"https:\/\/sicanivillages.com\/fr\/le-reve-dun-revenant-sicilien-se-realise-dans-lentreprise-familiale\/#primaryimage"},"thumbnailUrl":"https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/11\/Giangiuffre-3-scaled.jpeg","datePublished":"2023-11-25T15:05:53+00:00","dateModified":"2025-02-24T12:26:36+00:00","author":{"@id":"https:\/\/sicanivillages.com\/#\/schema\/person\/0e21e04294f29467d1ed2340219cb5eb"},"breadcrumb":{"@id":"https:\/\/sicanivillages.com\/fr\/le-reve-dun-revenant-sicilien-se-realise-dans-lentreprise-familiale\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sicanivillages.com\/fr\/le-reve-dun-revenant-sicilien-se-realise-dans-lentreprise-familiale\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/sicanivillages.com\/fr\/le-reve-dun-revenant-sicilien-se-realise-dans-lentreprise-familiale\/#primaryimage","url":"https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/11\/Giangiuffre-3-scaled.jpeg","contentUrl":"https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/11\/Giangiuffre-3-scaled.jpeg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/sicanivillages.com\/fr\/le-reve-dun-revenant-sicilien-se-realise-dans-lentreprise-familiale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sicanivillages.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Le r\u00eave d&rsquo;un revenant sicilien se r\u00e9alise dans l&rsquo;entreprise familiale"}]},{"@type":"WebSite","@id":"https:\/\/sicanivillages.com\/#website","url":"https:\/\/sicanivillages.com\/","name":"SicaniVillages","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sicanivillages.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/sicanivillages.com\/#\/schema\/person\/0e21e04294f29467d1ed2340219cb5eb","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/sicanivillages.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c8879fbd1a1b23ce6e384dc15d3f74c42237fbcedd0e0753c04d3103a5a3db4c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c8879fbd1a1b23ce6e384dc15d3f74c42237fbcedd0e0753c04d3103a5a3db4c?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/sicanivillages.com\/fr\/author\/sicanivillages\/"}]}},"_links":{"self":[{"href":"https:\/\/sicanivillages.com\/fr\/wp-json\/wp\/v2\/posts\/14587","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sicanivillages.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sicanivillages.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sicanivillages.com\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/sicanivillages.com\/fr\/wp-json\/wp\/v2\/comments?post=14587"}],"version-history":[{"count":7,"href":"https:\/\/sicanivillages.com\/fr\/wp-json\/wp\/v2\/posts\/14587\/revisions"}],"predecessor-version":[{"id":14636,"href":"https:\/\/sicanivillages.com\/fr\/wp-json\/wp\/v2\/posts\/14587\/revisions\/14636"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sicanivillages.com\/fr\/wp-json\/wp\/v2\/media\/12374"}],"wp:attachment":[{"href":"https:\/\/sicanivillages.com\/fr\/wp-json\/wp\/v2\/media?parent=14587"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sicanivillages.com\/fr\/wp-json\/wp\/v2\/categories?post=14587"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sicanivillages.com\/fr\/wp-json\/wp\/v2\/tags?post=14587"},{"taxonomy":"mese","embeddable":true,"href":"https:\/\/sicanivillages.com\/fr\/wp-json\/wp\/v2\/mese?post=14587"},{"taxonomy":"paese","embeddable":true,"href":"https:\/\/sicanivillages.com\/fr\/wp-json\/wp\/v2\/paese?post=14587"},{"taxonomy":"tipologia","embeddable":true,"href":"https:\/\/sicanivillages.com\/fr\/wp-json\/wp\/v2\/tipologia?post=14587"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}