{"id":13357,"date":"2023-12-11T14:01:49","date_gmt":"2023-12-11T14:01:49","guid":{"rendered":"https:\/\/sicanivillages.com\/fete-de-saint-antoine-abbe\/"},"modified":"2025-02-17T16:33:11","modified_gmt":"2025-02-17T16:33:11","slug":"fete-de-saint-antoine-abbe","status":"publish","type":"post","link":"https:\/\/sicanivillages.com\/fr\/fete-de-saint-antoine-abbe\/","title":{"rendered":"F\u00eate de Saint Antoine Abb\u00e9"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"13357\" class=\"elementor elementor-13357 elementor-10536\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1743bb46 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1743bb46\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4fe7966\" data-id=\"4fe7966\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-485115e elementor-widget elementor-widget-text-editor\" data-id=\"485115e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.19.0 - 07-02-2024 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<p><\/p>\n<h4>Burgio &#8211; 17 janvier<\/h4>\n<p><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-03a3392 elementor-widget elementor-widget-text-editor\" data-id=\"03a3392\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h1>F\u00eate de Saint Antoine Abb\u00e9<\/h1>\n<div> <\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-762fe9a elementor-widget elementor-widget-text-editor\" data-id=\"762fe9a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\n<p>Le soir de la veille, les enfants mettent le feu \u00e0 un tas de bois pr\u00e9par\u00e9 les jours pr\u00e9c\u00e9dents. Le rituel du feu pr\u00e9c\u00e8de la f\u00eate du lendemain, au cours de laquelle les produits de la terre et les animaux dont le saint patron est b\u00e9ni.  <\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1c16676 elementor-widget elementor-widget-image\" data-id=\"1c16676\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.19.0 - 07-02-2024 *\/\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" width=\"1500\" height=\"1500\" src=\"https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/12\/Placeholder-2.jpg\" class=\"elementor-animation-sink attachment-full size-full wp-image-10526\" alt=\"\" srcset=\"https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/12\/Placeholder-2.jpg 1500w, https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/12\/Placeholder-2-300x300.jpg 300w, https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/12\/Placeholder-2-1024x1024.jpg 1024w, https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/12\/Placeholder-2-150x150.jpg 150w, https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/12\/Placeholder-2-768x768.jpg 768w, https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/12\/Placeholder-2-636x636.jpg 636w, https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/12\/Placeholder-2-306x306.jpg 306w, https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/12\/Placeholder-2-600x600.jpg 600w, https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/12\/Placeholder-2-100x100.jpg 100w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f35f526 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f35f526\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-52100c0\" data-id=\"52100c0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2046669 elementor-widget elementor-widget-text-editor\" data-id=\"2046669\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\n<p><strong>Saint Antoine Abb\u00e9<\/strong> est \u00e9galement invoqu\u00e9 pour \u00eatre pr\u00e9serv\u00e9 du feu et des incendies. Lors du festival en son honneur, la statue le repr\u00e9sentant est port\u00e9e en procession dans les rues du centre ville, suivie par une multitude de croyants.<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a688a43 elementor-widget elementor-widget-image-carousel\" data-id=\"a688a43\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;2&quot;,&quot;slides_to_scroll&quot;:&quot;2&quot;,&quot;navigation&quot;:&quot;none&quot;,&quot;autoplay&quot;:&quot;no&quot;,&quot;infinite&quot;:&quot;no&quot;,&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:15,&quot;sizes&quot;:[]},&quot;slides_to_show_mobile&quot;:&quot;2&quot;,&quot;slides_to_scroll_mobile&quot;:&quot;2&quot;,&quot;speed&quot;:500,&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.19.0 - 07-02-2024 *\/\n.elementor-widget-image-carousel .swiper,.elementor-widget-image-carousel .swiper-container{position:static}.elementor-widget-image-carousel .swiper-container .swiper-slide figure,.elementor-widget-image-carousel .swiper .swiper-slide figure{line-height:inherit}.elementor-widget-image-carousel .swiper-slide{text-align:center}.elementor-image-carousel-wrapper:not(.swiper-container-initialized):not(.swiper-initialized) .swiper-slide{max-width:calc(100% \/ var(--e-image-carousel-slides-to-show, 3))}<\/style>\t\t<div class=\"elementor-image-carousel-wrapper swiper\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"polite\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 sur 2\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"a688a43\" data-elementor-lightbox-title=\"Placeholder nuovo\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6ODk4NywidXJsIjoiaHR0cHM6XC9cL3NpY2FuaXZpbGxhZ2VzLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyM1wvMDlcL1BsYWNlaG9sZGVyLW51b3ZvLmpwZyIsInNsaWRlc2hvdyI6ImE2ODhhNDMifQ%3D%3D\" href=\"https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/09\/Placeholder-nuovo.jpg\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/09\/Placeholder-nuovo-768x660.jpg\" alt=\"Placeholder nuovo\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 sur 2\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"a688a43\" data-elementor-lightbox-title=\"Placeholder 2\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTA1MjYsInVybCI6Imh0dHBzOlwvXC9zaWNhbml2aWxsYWdlcy5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjNcLzEyXC9QbGFjZWhvbGRlci0yLmpwZyIsInNsaWRlc2hvdyI6ImE2ODhhNDMifQ%3D%3D\" href=\"https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/12\/Placeholder-2.jpg\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/12\/Placeholder-2-768x660.jpg\" alt=\"Placeholder 2\" \/><\/figure><\/a><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b7be992 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b7be992\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-e2909cb\" data-id=\"e2909cb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3931a44\" data-id=\"3931a44\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-42c64ca elementor-align-center elementor-widget elementor-widget-button\" data-id=\"42c64ca\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-lg\" href=\"https:\/\/sicanivillages.com\/fr\/evenements\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Retour aux \u00e9v\u00e9nements<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-4f123e7\" data-id=\"4f123e7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Burgio<\/p>\n","protected":false},"author":2,"featured_media":12416,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"image","meta":{"_acf_changed":false,"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","footnotes":""},"categories":[145],"tags":[],"mese":[180],"paese":[114],"tipologia":[169],"class_list":["post-13357","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-evenements","post_format-post-format-image","mese-janvier","paese-burgio","tipologia-fetes-religieuses"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>F\u00eate de Saint Antoine Abb\u00e9 - SicaniVillages<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sicanivillages.com\/fr\/fete-de-saint-antoine-abbe\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"F\u00eate de Saint Antoine Abb\u00e9 - SicaniVillages\" \/>\n<meta property=\"og:description\" content=\"Burgio\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sicanivillages.com\/fr\/fete-de-saint-antoine-abbe\/\" \/>\n<meta property=\"og:site_name\" content=\"SicaniVillages\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-11T14:01:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-17T16:33:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/12\/Placeholder-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Maurizio Alfieri\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Maurizio Alfieri\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/sicanivillages.com\/fr\/fete-de-saint-antoine-abbe\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/sicanivillages.com\/fr\/fete-de-saint-antoine-abbe\/\"},\"author\":{\"name\":\"Maurizio Alfieri\",\"@id\":\"https:\/\/sicanivillages.com\/#\/schema\/person\/cd19c7b42eaf4adfa169fd88ed7938eb\"},\"headline\":\"F\u00eate de Saint Antoine Abb\u00e9\",\"datePublished\":\"2023-12-11T14:01:49+00:00\",\"dateModified\":\"2025-02-17T16:33:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/sicanivillages.com\/fr\/fete-de-saint-antoine-abbe\/\"},\"wordCount\":116,\"image\":{\"@id\":\"https:\/\/sicanivillages.com\/fr\/fete-de-saint-antoine-abbe\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/12\/Placeholder-2.jpg\",\"articleSection\":[\"Ev\u00e9nements\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/sicanivillages.com\/fr\/fete-de-saint-antoine-abbe\/\",\"url\":\"https:\/\/sicanivillages.com\/fr\/fete-de-saint-antoine-abbe\/\",\"name\":\"F\u00eate de Saint Antoine Abb\u00e9 - SicaniVillages\",\"isPartOf\":{\"@id\":\"https:\/\/sicanivillages.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/sicanivillages.com\/fr\/fete-de-saint-antoine-abbe\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/sicanivillages.com\/fr\/fete-de-saint-antoine-abbe\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/12\/Placeholder-2.jpg\",\"datePublished\":\"2023-12-11T14:01:49+00:00\",\"dateModified\":\"2025-02-17T16:33:11+00:00\",\"author\":{\"@id\":\"https:\/\/sicanivillages.com\/#\/schema\/person\/cd19c7b42eaf4adfa169fd88ed7938eb\"},\"breadcrumb\":{\"@id\":\"https:\/\/sicanivillages.com\/fr\/fete-de-saint-antoine-abbe\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/sicanivillages.com\/fr\/fete-de-saint-antoine-abbe\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/sicanivillages.com\/fr\/fete-de-saint-antoine-abbe\/#primaryimage\",\"url\":\"https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/12\/Placeholder-2.jpg\",\"contentUrl\":\"https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/12\/Placeholder-2.jpg\",\"width\":1500,\"height\":1500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/sicanivillages.com\/fr\/fete-de-saint-antoine-abbe\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/sicanivillages.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"F\u00eate de Saint Antoine Abb\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/sicanivillages.com\/#website\",\"url\":\"https:\/\/sicanivillages.com\/\",\"name\":\"SicaniVillages\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/sicanivillages.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/sicanivillages.com\/#\/schema\/person\/cd19c7b42eaf4adfa169fd88ed7938eb\",\"name\":\"Maurizio Alfieri\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/sicanivillages.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/dfda2d8fb54c9e404e0a67984650a6963ecb4c562a0b76969fc49d2549baae34?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/dfda2d8fb54c9e404e0a67984650a6963ecb4c562a0b76969fc49d2549baae34?s=96&d=mm&r=g\",\"caption\":\"Maurizio Alfieri\"},\"url\":\"https:\/\/sicanivillages.com\/fr\/author\/maustakkio\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"F\u00eate de Saint Antoine Abb\u00e9 - SicaniVillages","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sicanivillages.com\/fr\/fete-de-saint-antoine-abbe\/","og_locale":"fr_FR","og_type":"article","og_title":"F\u00eate de Saint Antoine Abb\u00e9 - SicaniVillages","og_description":"Burgio","og_url":"https:\/\/sicanivillages.com\/fr\/fete-de-saint-antoine-abbe\/","og_site_name":"SicaniVillages","article_published_time":"2023-12-11T14:01:49+00:00","article_modified_time":"2025-02-17T16:33:11+00:00","og_image":[{"width":1500,"height":1500,"url":"https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/12\/Placeholder-2.jpg","type":"image\/jpeg"}],"author":"Maurizio Alfieri","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Maurizio Alfieri","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sicanivillages.com\/fr\/fete-de-saint-antoine-abbe\/#article","isPartOf":{"@id":"https:\/\/sicanivillages.com\/fr\/fete-de-saint-antoine-abbe\/"},"author":{"name":"Maurizio Alfieri","@id":"https:\/\/sicanivillages.com\/#\/schema\/person\/cd19c7b42eaf4adfa169fd88ed7938eb"},"headline":"F\u00eate de Saint Antoine Abb\u00e9","datePublished":"2023-12-11T14:01:49+00:00","dateModified":"2025-02-17T16:33:11+00:00","mainEntityOfPage":{"@id":"https:\/\/sicanivillages.com\/fr\/fete-de-saint-antoine-abbe\/"},"wordCount":116,"image":{"@id":"https:\/\/sicanivillages.com\/fr\/fete-de-saint-antoine-abbe\/#primaryimage"},"thumbnailUrl":"https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/12\/Placeholder-2.jpg","articleSection":["Ev\u00e9nements"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/sicanivillages.com\/fr\/fete-de-saint-antoine-abbe\/","url":"https:\/\/sicanivillages.com\/fr\/fete-de-saint-antoine-abbe\/","name":"F\u00eate de Saint Antoine Abb\u00e9 - SicaniVillages","isPartOf":{"@id":"https:\/\/sicanivillages.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sicanivillages.com\/fr\/fete-de-saint-antoine-abbe\/#primaryimage"},"image":{"@id":"https:\/\/sicanivillages.com\/fr\/fete-de-saint-antoine-abbe\/#primaryimage"},"thumbnailUrl":"https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/12\/Placeholder-2.jpg","datePublished":"2023-12-11T14:01:49+00:00","dateModified":"2025-02-17T16:33:11+00:00","author":{"@id":"https:\/\/sicanivillages.com\/#\/schema\/person\/cd19c7b42eaf4adfa169fd88ed7938eb"},"breadcrumb":{"@id":"https:\/\/sicanivillages.com\/fr\/fete-de-saint-antoine-abbe\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sicanivillages.com\/fr\/fete-de-saint-antoine-abbe\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/sicanivillages.com\/fr\/fete-de-saint-antoine-abbe\/#primaryimage","url":"https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/12\/Placeholder-2.jpg","contentUrl":"https:\/\/sicanivillages.com\/wp-content\/uploads\/2023\/12\/Placeholder-2.jpg","width":1500,"height":1500},{"@type":"BreadcrumbList","@id":"https:\/\/sicanivillages.com\/fr\/fete-de-saint-antoine-abbe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sicanivillages.com\/fr\/"},{"@type":"ListItem","position":2,"name":"F\u00eate de Saint Antoine Abb\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/sicanivillages.com\/#website","url":"https:\/\/sicanivillages.com\/","name":"SicaniVillages","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sicanivillages.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/sicanivillages.com\/#\/schema\/person\/cd19c7b42eaf4adfa169fd88ed7938eb","name":"Maurizio Alfieri","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/sicanivillages.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/dfda2d8fb54c9e404e0a67984650a6963ecb4c562a0b76969fc49d2549baae34?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/dfda2d8fb54c9e404e0a67984650a6963ecb4c562a0b76969fc49d2549baae34?s=96&d=mm&r=g","caption":"Maurizio Alfieri"},"url":"https:\/\/sicanivillages.com\/fr\/author\/maustakkio\/"}]}},"_links":{"self":[{"href":"https:\/\/sicanivillages.com\/fr\/wp-json\/wp\/v2\/posts\/13357","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sicanivillages.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sicanivillages.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sicanivillages.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sicanivillages.com\/fr\/wp-json\/wp\/v2\/comments?post=13357"}],"version-history":[{"count":6,"href":"https:\/\/sicanivillages.com\/fr\/wp-json\/wp\/v2\/posts\/13357\/revisions"}],"predecessor-version":[{"id":14384,"href":"https:\/\/sicanivillages.com\/fr\/wp-json\/wp\/v2\/posts\/13357\/revisions\/14384"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sicanivillages.com\/fr\/wp-json\/wp\/v2\/media\/12416"}],"wp:attachment":[{"href":"https:\/\/sicanivillages.com\/fr\/wp-json\/wp\/v2\/media?parent=13357"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sicanivillages.com\/fr\/wp-json\/wp\/v2\/categories?post=13357"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sicanivillages.com\/fr\/wp-json\/wp\/v2\/tags?post=13357"},{"taxonomy":"mese","embeddable":true,"href":"https:\/\/sicanivillages.com\/fr\/wp-json\/wp\/v2\/mese?post=13357"},{"taxonomy":"paese","embeddable":true,"href":"https:\/\/sicanivillages.com\/fr\/wp-json\/wp\/v2\/paese?post=13357"},{"taxonomy":"tipologia","embeddable":true,"href":"https:\/\/sicanivillages.com\/fr\/wp-json\/wp\/v2\/tipologia?post=13357"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}